{"id":1472,"date":"2020-09-14T13:03:18","date_gmt":"2020-09-14T11:03:18","guid":{"rendered":"https:\/\/mstholdingblog.com\/?p=1472"},"modified":"2023-06-06T16:56:54","modified_gmt":"2023-06-06T14:56:54","slug":"estais-preparados-para-asumir-el-volumen-total-de-llamadas","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/","title":{"rendered":"\u00bfEst\u00e1is preparados para asumir el volumen total de llamadas?"},"content":{"rendered":"<h2><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-1479\" src=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/09\/linkedin-linea-blanca-MST-1024x536.jpg\" alt=\"\u00bfPreparados para asumir el volumen total de llamadas?\" width=\"621\" height=\"325\" \/><\/h2>\n<h2>Con la vuelta al cole y el fin de las vacaciones muchos son los clientes que llaman para arreglar electrodom\u00e9sticos o preparar la revisi\u00f3n de la caldera<\/h2>\n<p>El volumen total de llamadas en un servicio de Atenci\u00f3n al Cliente acostumbra a ser mayor en septiembre. La vuelta al cole, el fin de las vacaciones o el descenso de las temperaturas son s\u00edntomas de problemas. A continuaci\u00f3n, os presentamos algunas situaciones en que las empresas sufren un desbordamiento de llamadas y el tiempo de espera es mayor al habitual. Por este motivo, <strong>en MST Holding os tendemos la mano por si quisierais externalizar aquellos servicios puntuales en los que no podr\u00e9is asumir todas las llamadas.<\/strong> <strong>Tener satisfecho al cliente es el bien m\u00e1s preciado.<\/strong><\/p>\n<p>Mira tambi\u00e9n las peyorativas que vienen en <a href=\"https:\/\/mstholdingblog.com\/2020\/09\/16\/la-revolucion-del-sector-financiero-y-asegurador\/\" target=\"_blank\" rel=\"noopener noreferrer\">el sector financiero y asegurador.<\/a><\/p>\n<h3>Electrodom\u00e9sticos y energ\u00eda<\/h3>\n<p>Seg\u00fan el Reglamento de las Instalaciones T\u00e9rmicas en los Edificios (RITE) dicta que cada dos a\u00f1os hay que realizar una revisi\u00f3n de la caldera\u00a0<strong>de manera obligatoria<\/strong>. \u00bfCuando hay que hacerla? Antes de que venga el fr\u00edo y nos pille el toro. Entre septiembre y octubre es el tiempo que m\u00e1s llamadas realizamos a empresas suministradoras de energ\u00eda para realizar la revisi\u00f3n de la caldera o para comprar una de nuevo.<\/p>\n<p>Adem\u00e1s, en estos meses tambi\u00e9n queremos arreglar aquellos electrodom\u00e9sticos que fallaban antes de irnos de vacaciones. Ahora, con la vuelta a la normalidad y a v\u00edsperas de lo que pueda pasar con el Covid-19, <strong>m\u00e1s vale p\u00e1jaro en mano que ciento volando.<\/strong> Muchos son los clientes que llaman para arreglar la impresora, o porque el lavavajillas est\u00e1 dando problemas o la lavadora no funciona correctamente.<\/p>\n<p><strong>\u00bfEst\u00e1is preparados para asumir el volumen total de llamadas?<\/strong><\/p>\n<p>Si est\u00e1s leyendo esto y ves que en tu empresa vais a tener un problema, <a href=\"https:\/\/www.mstholding.com\/ES\/Contacto.html\" target=\"_blank\" rel=\"noopener noreferrer\">no dudes en contactar con nosotros.<\/a><\/p>\n<p>En MST ofrecemos un amplio abanico de servicios que cubren todas las necesidades end-to-end en el \u00e1mbito del Customer Service.<\/p>\n<p>\u00bfQuieres conocernos un poco m\u00e1s?\u00a0<strong><a href=\"https:\/\/www.mstholding.com\/ES\/MstHolding.html\" target=\"_blank\" rel=\"noopener noreferrer\">Entra en nuestra web <\/a><\/strong>O, rellena el formulario y nos pondremos en contacto contigo.<\/p>\n<p><a href=\"https:\/\/mstholdingblog.com\/category\/noticias\/\" target=\"_blank\" rel=\"noopener noreferrer\">Te interesa saber\u2026<\/a><\/p>\n<p>Sigue nuestras cuentas en Linkedin para estar al d\u00eda de todo.\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/318189\/\" target=\"_blank\" rel=\"noopener noreferrer\">MST<\/a>\u00a0\/\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/1490090\/\" target=\"_blank\" rel=\"noopener noreferrer\">C3<\/a>\u00a0\/\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/2531794\/\" target=\"_blank\" rel=\"noopener noreferrer\">eAlicia<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la vuelta al cole y el fin de las vacaciones muchos son los clientes que llaman para arreglar electrodom\u00e9sticos o preparar la revisi\u00f3n de la caldera El volumen total de llamadas en un servicio de Atenci\u00f3n al Cliente acostumbra a ser mayor en septiembre. La vuelta al cole, el fin de las vacaciones o [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[10],"class_list":["post-1472","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-antencion-al-cliente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>\u00bfPreparados para asumir el volumen total de llamadas? - MST Holding Blog<\/title>\r\n<meta name=\"description\" content=\"El volumen total de llamadas en un servicio de Atenci\u00f3n al Cliente acostumbra a ser mayor en septiembre. \u00bfEst\u00e1 tu empresa preparada?\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"\u00bfPreparados para asumir el volumen total de llamadas? - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"El volumen total de llamadas en un servicio de Atenci\u00f3n al Cliente acostumbra a ser mayor en septiembre. \u00bfEst\u00e1 tu empresa preparada?\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-09-14T11:03:18+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:56:54+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/09\/linkedin-linea-blanca-MST-1024x536.jpg\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"\u00bfEst\u00e1is preparados para asumir el volumen total de llamadas?\",\"datePublished\":\"2020-09-14T11:03:18+00:00\",\"dateModified\":\"2023-06-06T14:56:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/\"},\"wordCount\":398,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/linkedin-linea-blanca-MST-1024x536.jpg\",\"keywords\":[\"antenci\u00f3n al cliente\"],\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/\",\"name\":\"\u00bfPreparados para asumir el volumen total de llamadas? - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/linkedin-linea-blanca-MST-1024x536.jpg\",\"datePublished\":\"2020-09-14T11:03:18+00:00\",\"dateModified\":\"2023-06-06T14:56:54+00:00\",\"description\":\"El volumen total de llamadas en un servicio de Atenci\u00f3n al Cliente acostumbra a ser mayor en septiembre. \u00bfEst\u00e1 tu empresa preparada?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/linkedin-linea-blanca-MST-1024x536.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/linkedin-linea-blanca-MST-1024x536.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEst\u00e1is preparados para asumir el volumen total de llamadas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPreparados para asumir el volumen total de llamadas? - MST Holding Blog","description":"El volumen total de llamadas en un servicio de Atenci\u00f3n al Cliente acostumbra a ser mayor en septiembre. \u00bfEst\u00e1 tu empresa preparada?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPreparados para asumir el volumen total de llamadas? - MST Holding Blog","og_description":"El volumen total de llamadas en un servicio de Atenci\u00f3n al Cliente acostumbra a ser mayor en septiembre. \u00bfEst\u00e1 tu empresa preparada?","og_url":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/","og_site_name":"MST Holding Blog","article_published_time":"2020-09-14T11:03:18+00:00","article_modified_time":"2023-06-06T14:56:54+00:00","og_image":[{"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/09\/linkedin-linea-blanca-MST-1024x536.jpg","type":"","width":"","height":""}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"\u00bfEst\u00e1is preparados para asumir el volumen total de llamadas?","datePublished":"2020-09-14T11:03:18+00:00","dateModified":"2023-06-06T14:56:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/"},"wordCount":398,"commentCount":1,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/09\/linkedin-linea-blanca-MST-1024x536.jpg","keywords":["antenci\u00f3n al cliente"],"articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/","url":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/","name":"\u00bfPreparados para asumir el volumen total de llamadas? - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/09\/linkedin-linea-blanca-MST-1024x536.jpg","datePublished":"2020-09-14T11:03:18+00:00","dateModified":"2023-06-06T14:56:54+00:00","description":"El volumen total de llamadas en un servicio de Atenci\u00f3n al Cliente acostumbra a ser mayor en septiembre. \u00bfEst\u00e1 tu empresa preparada?","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/09\/linkedin-linea-blanca-MST-1024x536.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/09\/linkedin-linea-blanca-MST-1024x536.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/estais-preparados-para-asumir-el-volumen-total-de-llamadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfEst\u00e1is preparados para asumir el volumen total de llamadas?"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/1472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=1472"}],"version-history":[{"count":1,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/1472\/revisions"}],"predecessor-version":[{"id":3531,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/1472\/revisions\/3531"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=1472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=1472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=1472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}