{"id":154,"date":"2019-08-02T11:25:27","date_gmt":"2019-08-02T09:25:27","guid":{"rendered":"https:\/\/mstholdingblog.com\/?p=154"},"modified":"2023-06-06T16:59:46","modified_gmt":"2023-06-06T14:59:46","slug":"mstholding-new-partner-barcelona-global","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/","title":{"rendered":"MST Holding, new partner of Barcelona Global"},"content":{"rendered":"<p>Barcelona Global is responsible for attracting foreign talent to work in the Catalan capital.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-97\" src=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/barcelona-953904_1920-300x212.jpg\" alt=\"\" width=\"770\" height=\"544\" \/><\/p>\n<p>The Barcelona Global association has created a website with the aim of attracting international talent to the Catalan capital. The initiative, called Work in Barcelona, \u200b\u200baims to collect in the same portal <strong>all job offers that companies in Barcelona direct<\/strong> to foreign workers specialized in technology.<\/p>\n<p>The intention of Barcelona Global is to add the more companies better &#8211; at least \u00absome twenty\u00bb until the end of the year &#8211; and become the reference portal for job offers for foreigners in Barcelona. <strong>At MST Holding we are committed to the future and talent. With this initiative, we try to go further and attract foreign talent to our company.<\/strong><\/p>\n<p>In addition to collaborating in the experience of increasing the power of the \u00abBarcelona\u00bb brand, the association believes that its initiative will also contribute to positioning Barcelona as a city to work in the digital sector, precisely one of the areas that recorded the highest growth in recent years and that regrets the lack of digital talent in the city. For this reason, Work in Barcelona is planned to be integrated into Barcelona Digital Talent, the public-private initiative promoted by <strong>Mobile World Capital, CTecno, Barcelona Tech City, 22 @ Network, Barcelona Global, Foment del Treball, Generalitat and the City Council from Barcelona.<\/strong><\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/company\/\">Follow us on our social networks to not miss anything!<\/a><\/p>\n<p><a href=\"https:\/\/mstholdingblog.com\/en\/\">I want to know&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barcelona Global is responsible for attracting foreign talent to work in the Catalan capital. The Barcelona Global association has created a website with the aim of attracting international talent to the Catalan capital. The initiative, called Work in Barcelona, \u200b\u200baims to collect in the same portal all job offers that companies in Barcelona direct to [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[234],"tags":[],"class_list":["post-154","post","type-post","status-publish","format-standard","hentry","category-news-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>MST Holding, new partner of Barcelona Global -<\/title>\r\n<meta name=\"description\" content=\"La asociaci\u00f3n\u00a0Barcelona Global pretende recoger en un portal las\u00a0ofertas de empleo a\u00a0trabajadores extranjeros especializados en tecnolog\u00eda.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"MST Holding, new partner of Barcelona Global -\" \/>\r\n<meta property=\"og:description\" content=\"La asociaci\u00f3n\u00a0Barcelona Global pretende recoger en un portal las\u00a0ofertas de empleo a\u00a0trabajadores extranjeros especializados en tecnolog\u00eda.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2019-08-02T09:25:27+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:59:46+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/barcelona-953904_1920-300x212.jpg\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"MST Holding, new partner of Barcelona Global\",\"datePublished\":\"2019-08-02T09:25:27+00:00\",\"dateModified\":\"2023-06-06T14:59:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/\"},\"wordCount\":243,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/barcelona-953904_1920-300x212.jpg\",\"articleSection\":[\"NEWS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/\",\"name\":\"MST Holding, new partner of Barcelona Global -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/barcelona-953904_1920-300x212.jpg\",\"datePublished\":\"2019-08-02T09:25:27+00:00\",\"dateModified\":\"2023-06-06T14:59:46+00:00\",\"description\":\"La asociaci\u00f3n\u00a0Barcelona Global pretende recoger en un portal las\u00a0ofertas de empleo a\u00a0trabajadores extranjeros especializados en tecnolog\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/barcelona-953904_1920-300x212.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/barcelona-953904_1920-300x212.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/en\\\/mstholding-new-partner-barcelona-global\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MST Holding, new partner of Barcelona Global\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MST Holding, new partner of Barcelona Global -","description":"La asociaci\u00f3n\u00a0Barcelona Global pretende recoger en un portal las\u00a0ofertas de empleo a\u00a0trabajadores extranjeros especializados en tecnolog\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/","og_locale":"es_ES","og_type":"article","og_title":"MST Holding, new partner of Barcelona Global -","og_description":"La asociaci\u00f3n\u00a0Barcelona Global pretende recoger en un portal las\u00a0ofertas de empleo a\u00a0trabajadores extranjeros especializados en tecnolog\u00eda.","og_url":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/","og_site_name":"MST Holding Blog","article_published_time":"2019-08-02T09:25:27+00:00","article_modified_time":"2023-06-06T14:59:46+00:00","og_image":[{"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/barcelona-953904_1920-300x212.jpg","type":"","width":"","height":""}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"MST Holding, new partner of Barcelona Global","datePublished":"2019-08-02T09:25:27+00:00","dateModified":"2023-06-06T14:59:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/"},"wordCount":243,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/barcelona-953904_1920-300x212.jpg","articleSection":["NEWS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/","url":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/","name":"MST Holding, new partner of Barcelona Global -","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/barcelona-953904_1920-300x212.jpg","datePublished":"2019-08-02T09:25:27+00:00","dateModified":"2023-06-06T14:59:46+00:00","description":"La asociaci\u00f3n\u00a0Barcelona Global pretende recoger en un portal las\u00a0ofertas de empleo a\u00a0trabajadores extranjeros especializados en tecnolog\u00eda.","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/barcelona-953904_1920-300x212.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/barcelona-953904_1920-300x212.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/en\/mstholding-new-partner-barcelona-global\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"MST Holding, new partner of Barcelona Global"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=154"}],"version-history":[{"count":1,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/154\/revisions"}],"predecessor-version":[{"id":2116,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/154\/revisions\/2116"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}