{"id":1588,"date":"2020-10-09T09:58:53","date_gmt":"2020-10-09T07:58:53","guid":{"rendered":"https:\/\/mstholdingblog.com\/?p=1588"},"modified":"2023-06-06T16:56:50","modified_gmt":"2023-06-06T14:56:50","slug":"los-errores-mas-frecuentes-de-establecer-kpis","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/","title":{"rendered":"Los errores m\u00e1s frecuentes de establecer KPI&#8217;s"},"content":{"rendered":"<h2><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-1592\" src=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/10\/linkedin-10-errores-kpis-eAlicia-1024x536.jpg\" alt=\"10 errores KPIs\" width=\"511\" height=\"267\" \/><\/h2>\n<h2>Conocer cu\u00e1l es el impacto que tu producto, servicio o marca tiene sobre tus clientes es fundamental para saber por qu\u00e9 les gustas o no<\/h2>\n<p id=\"viewer-6pibp\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Establecer KPIs puede ser m\u00e1s complicado de lo que parece. Tienes que definir KPI\u2019s para conocer cu\u00e1l es el impacto que tu producto, servicio o marca tiene sobre tus clientes. Es fundamental para saber por qu\u00e9 les gustas o no les gustas, es decir, por qu\u00e9 te compran o no te compran. <a href=\"https:\/\/mstholdingblog.com\/2020\/09\/10\/plataforma-customer-experience-360o\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mira tambi\u00e9n c\u00f3mo puedes mejorar tus servicios.<\/a><\/p>\n<p id=\"viewer-601ak\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Sin elementos que te permitan medir su experiencia te va a ser imposible\u00a0<strong>entender el comportamiento de tus clientes<\/strong>, tanto si es a tu favor como, sobre todo, en tu contra. Como dijo William Thomson,\u00a0<strong>\u201cTodo lo que no se puede medir, no se puede mejorar\u201d.<\/strong>\u00a0Por eso, si no dispones elementos de medici\u00f3n de la calidad de tu producto o servicio, o de la calidad de la experiencia de tus clientes, o de la calidad y funcionalidad de tus procesos internos, no te ser\u00e1 posible detectar en qu\u00e9 est\u00e1s fallando y, menos a\u00fan,\u00a0<strong>determinar la \u00f3ptima estrategia para mejorar<\/strong>.<\/p>\n<p id=\"viewer-b7d1u\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">En cualquier caso, para medir necesitas\u00a0<strong>datos objetivos<\/strong>\u00a0que te expliquen\u00a0<strong><em>qu\u00e9<\/em><\/strong>,\u00a0<strong><em>d\u00f3nde<\/em><\/strong>,\u00a0<strong><em>c\u00f3mo<\/em><\/strong>,\u00a0<strong><em>cu\u00e1nto<\/em><\/strong>\u00a0y\u00a0<strong><em>cu\u00e1ndo<\/em><\/strong>. Esos datos son los\u00a0<strong>indicadores clave de rendimiento\u00a0<\/strong><em>(o KPI\u2019s)<\/em>\u00a0de aquello que quieres medir y son como el term\u00f3metro para la fiebre. Otro dato importante es el\u00a0<strong><em>por qu\u00e9<\/em><\/strong>, que nacer\u00e1 de tu an\u00e1lisis, facilit\u00e1ndote un diagn\u00f3stico muy preciso, que ofrecer\u00e1 mejores resultados.<\/p>\n<p>Si quieres profundizar en la creaci\u00f3n y establecer KPis adecuados, puedes consultarnos para encontrar una formaci\u00f3n a medida y adecuada a tus necesidades, que te sirva para establecer indicadores efectivos en funci\u00f3n de criterios estrat\u00e9gicos y operativos, as\u00ed como conocer las fases de definici\u00f3n, creaci\u00f3n e implementaci\u00f3n. Para ello, no te pierdas nuestro curso en <a class=\"_2qJYG blog-link-hashtag-color _2xVcV\" href=\"https:\/\/www.consultingc3.com\/Curso-Gestion-KPIs.html\" target=\"_blank\" rel=\"noopener noreferrer\"><u class=\"sDZYg\"><strong>creaci\u00f3n y gesti\u00f3n de KPIs<\/strong><\/u><\/a>.<\/p>\n<h3 id=\"viewer-ajvt8\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>\u00bfC\u00f3mo saber qu\u00e9 indicadores debo utilizar?<\/strong><\/h3>\n<p id=\"viewer-55eh4\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Implementar los indicadores adecuados parece tarea f\u00e1cil si conoces m\u00e1s o menos aquello que quieres medir. En l\u00edneas generales, mostramos\u00a0<strong>tendencia a medirlo todo<\/strong>\u00a0para que no se nos escape nada. As\u00ed, partimos de la idea de que cuanto m\u00e1s midamos, m\u00e1s conoceremos a nuestros clientes. Sin embargo, como ocurre muchas veces, los excesos no son buenos y puede llegar un momento en que los \u00e1rboles no nos dejen ver el bosque.<\/p>\n<h3 id=\"viewer-459oc\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>10 errores frecuentes a la hora de definir los KPI\u2019s<\/strong><\/h3>\n<p>A continuaci\u00f3n, os explicamos c\u00f3mo no has de definir los KPI\u2019s.<\/p>\n<h3 id=\"viewer-a75ne\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>1. La medici\u00f3n no comporta acciones correctivas o de mejora<\/strong><\/h3>\n<p id=\"viewer-e88d1\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">La implementaci\u00f3n de KPI\u2019s comporta un compromiso de seguimiento preciso y riguroso, sin el cual \u00e9stos pierden su funcionalidad. Si un KPI no se eval\u00faa o no se realiza un correcto seguimiento;\u00a0<strong>si no sirve para hacer acciones de mejora<\/strong>, o las acciones no se llevan a cabo, el indicador no sirve de nada.<\/p>\n<p id=\"viewer-chna3\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Muchas veces, la vor\u00e1gine del trabajo diario o la falta de responsabilidades claras sobre la medici\u00f3n del KPI hace que su utilidad quede anulada.<\/p>\n<h3 id=\"viewer-2044b\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>2. S\u00edndrome de Di\u00f3genes<\/strong><\/h3>\n<p id=\"viewer-2rqe4\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">La man\u00eda de medirlo todo hace que acumulemos un mont\u00f3n de KPI\u2019s que no aportan valor. Nos parece que cuanto m\u00e1s midamos, m\u00e1s sabremos. \u00a1Y resulta que nos indigestamos de indicadores!<\/p>\n<p id=\"viewer-5ispd\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Cuando barajamos demasiados indicadores nos es imposible gestionarlos porque su evaluaci\u00f3n y seguimiento nos lleva demasiado tiempo.\u00a0<strong>\u00a1Suelta ese lastre y equilibra el valor del KPI con tu capacidad de gesti\u00f3n de la informaci\u00f3n!<\/strong><\/p>\n<h3 id=\"viewer-f7hho\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>3. El coleccionista de sue\u00f1os<\/strong><\/h3>\n<p id=\"viewer-fe54i\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">El hombre es un animal de costumbres. Y con los indicadores le pasa lo mismo.\u00a0<strong>Muchas veces mantenemos los mismos KPIs<\/strong>\u00a0porque son los que se han utilizado siempre. La pregunta que debes hacerte entonces es: \u00bfNo han cambiado mis clientes ni mi empresa en estos a\u00f1os? Recuerda renovar tu fondo de armario y mantener solo aquellos KPIs que te son \u00fatiles ahora. C\u00ed\u00f1ete a unos cu\u00e1ntos: s\u00f3lo a los que te aportan informaci\u00f3n valiosa para poder tomar decisiones.<\/p>\n<h3 id=\"viewer-bqlg7\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>4. Caer en el silo<\/strong><\/h3>\n<p id=\"viewer-a9v4p\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Los indicadores deben ser creados en base a una visi\u00f3n global del proceso. Cuando creamos KPI\u2019s pensando en los intereses de nuestro departamento y no de manera transversal y focaliz\u00e1ndonos en el cliente, estamos cayendo en lo que se denomina<strong>\u00a0\u201cefecto silo\u201d<\/strong>; es decir, nos convertimos en\u00a0<em>Golums<\/em>\u00a0que s\u00f3lo miran por conservar su tesoro. La comunicaci\u00f3n entre departamentos deja de fluir, deja de haber coordinaci\u00f3n y aparecen rivalidades, poniendo en jaque la consecuci\u00f3n de los objetivos globales.<\/p>\n<h3 id=\"viewer-asrog\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>5. El perfume de la vanidad<\/strong><\/h3>\n<p id=\"viewer-2p54b\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">A todos nos gusta quedar bien en la foto,\u00a0<strong>tapar nuestras verg\u00fcenzas<\/strong>\u00a0y, de paso, ahorrarnos una bronca del jefe. Por eso estamos tentados de \u201cmaquillar los resultados\u201d bas\u00e1ndonos en datos obtenidos con KPis vanidosos, cuyos datos dan a entender que todo va bien, pero que no nos aportan ning\u00fan valor real. Son muy peligrosos, puesto que no reflejan la realidad y nos pueden empujar a tomar decisiones basadas en an\u00e1lisis incorrectos.<\/p>\n<h3 id=\"viewer-8g2iv\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>6. La miop\u00eda cr\u00f3nica<\/strong><\/h3>\n<p id=\"viewer-bbp2a\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Cuando los indicadores ponen el foco en una parte sin tener en cuenta el todo,\u00a0<strong>es f\u00e1cil sacar conclusiones sesgadas<\/strong>\u00a0que nos hagan tomar decisiones err\u00f3neas. Por ejemplo, si un departamento de reparaciones detecta, a trav\u00e9s de un KPI mal definido, un elevado nivel de stock y decide reducirlo para ahorrar coste de inmovilizado, puede suponer que el servicio de asistencia t\u00e9cnica deba repetir el n\u00famero de intervenciones<em>\u00a0(m\u00e1s costes)<\/em>\u00a0y se pierdan clientes\u00a0<em>(\u00a1!)<\/em><\/p>\n<h3 id=\"viewer-5inqs\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>7. Mirarse el ombligo<\/strong><\/h3>\n<p id=\"viewer-2v013\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Pensar que ya sabemos qu\u00e9 medir sin haber escuchado al cliente es un error garrafal. Un restaurante med\u00eda la calidad de su servicio con varios\u00a0<strong>indicadores que valoraban la uniformidad<\/strong>, imagen y educaci\u00f3n de su personal. No estaban midiendo, sin embargo, el tiempo medio de espera de los clientes entre el primero y el segundo plato.<\/p>\n<h3 id=\"viewer-et34n\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>8. Trampas al Solitario<\/strong><\/h3>\n<p id=\"viewer-bgssq\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Esto puede suceder cuando el indicador se acaba convirtiendo en la finalidad; es decir, cuando el indicador estimula un objetivo o un comportamiento contraproducente en las personas.\u00a0<strong>Suelen ser indicadores que est\u00e1n asociados a\u00a0<em>bonus<\/em>\u00a0o compensaciones econ\u00f3micas<\/strong>. Por ejemplo: un indicador de productividad comercial que mida la ratio entre ofertas presentadas y ofertas aceptadas puede provocar que el comercial deje de presentar algunas ofertas para no perjudicar la ratio.<\/p>\n<h3 id=\"viewer-9sqdf\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>9. Piedras en el tejado<\/strong><\/h3>\n<p id=\"viewer-19fja\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Los indicadores deben estar alineados a los objetivos. Cuando\u00a0<strong>los KPIs entran en conflicto con los objetivos<\/strong>\u00a0se producen incongruencias operativas. Por ejemplo: un indicador que mida la rapidez en la entrega\u00a0<em>(n\u00ba de entregas en 24 horas)<\/em>\u00a0puede entrar en conflicto con un indicador de optimizaci\u00f3n log\u00edstica, como el de\u00a0<em>\u201cocupaci\u00f3n m\u00e1xima de la capacidad del transporte\u201d<\/em>. As\u00ed, para conseguir un buen resultado en el indicador de entregas en plazo, infrautilizamos los recursos log\u00edsticos, con salidas de camiones sin carga plena, lo que supone un aumento de costes y menor rentabilidad para la empresa.<\/p>\n<h3 id=\"viewer-8inpj\" class=\"_3tkn1 _208Ie blog-post-header-three-font blog-post-header-three-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\"><strong>10. Gato por liebre<\/strong><\/h3>\n<p id=\"viewer-7s4gd\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">El \u00faltimo de los errores m\u00e1s frecuentes se produce\u00a0<strong>al medir valores no fiables o no representativos<\/strong>, ya que no aportan valor a la toma de decisiones. Siempre que extraigamos datos, nos hemos de asegurar de que tanto las fuentes como el m\u00e9todo de extracci\u00f3n de esos datos sean fiables. Si extraemos datos tomados de una muestra, esta muestra debe ser representativa y extrapolable al total de los datos.<\/p>\n<p id=\"viewer-d2su2\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _1iXso wj-V5 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Desde eAlicia, te aconsejamos, para empezar, <strong>tomar consciencia de estos errores frecuentes para poder crear y gestionar indicadores<\/strong>\u00a0funcionales, que sean \u00fatiles a la toma de decisiones dentro de tu empresa.<\/p>\n<p id=\"viewer-ars7a\" class=\"XzvDs _208Ie ljrnk blog-post-text-font blog-post-text-color _2QAo- _25MYV _1Fao9 ljrnk public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr\">Pero esto es s\u00f3lo la punta del iceberg. Si quieres profundizar en la creaci\u00f3n y gesti\u00f3n de KPi\u2019s, puedes consultarnos para encontrar una formaci\u00f3n a medida y adecuada a tus necesidades, que te sirva para establecer indicadores efectivos en funci\u00f3n de criterios estrat\u00e9gicos y operativos, as\u00ed como conocer las fases de definici\u00f3n, creaci\u00f3n e implementaci\u00f3n. Para ello, no te pierdas nuestro curso en\u00a0<a class=\"_2qJYG blog-link-hashtag-color _2xVcV\" href=\"https:\/\/www.consultingc3.com\/Curso-Gestion-KPIs.html\" target=\"_blank\" rel=\"noopener noreferrer\"><u class=\"sDZYg\"><strong>creaci\u00f3n y gesti\u00f3n de KPIs<\/strong><\/u><\/a>.<\/p>\n<p><a href=\"https:\/\/consultingc3blog.com\/category\/noticias\/\" target=\"_blank\" rel=\"noopener noreferrer\">Te interesa saber\u2026<\/a><\/p>\n<p>Sigue nuestras cuentas en Linkedin para estar al d\u00eda de todo.\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/2531794\/\" target=\"_blank\" rel=\"noopener noreferrer\">eAlicia\/\u00a0<\/a><a href=\"https:\/\/www.linkedin.com\/company\/318189\/\" target=\"_blank\" rel=\"noopener noreferrer\">MST <\/a>\/ <a href=\"https:\/\/www.linkedin.com\/company\/1490090\/\" target=\"_blank\" rel=\"noopener noreferrer\">C3<\/a>\u00a0\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conocer cu\u00e1l es el impacto que tu producto, servicio o marca tiene sobre tus clientes es fundamental para saber por qu\u00e9 les gustas o no Establecer KPIs puede ser m\u00e1s complicado de lo que parece. Tienes que definir KPI\u2019s para conocer cu\u00e1l es el impacto que tu producto, servicio o marca tiene sobre tus clientes. [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-1588","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Los errores m\u00e1s frecuentes de establecer KPI&#039;s - MST Holding Blog<\/title>\r\n<meta name=\"description\" content=\"Establecer KPIs puede ser m\u00e1s complicado de lo que parece. En este art\u00edculo te explicamos 10 errores que no debes cometer.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Los errores m\u00e1s frecuentes de establecer KPI&#039;s - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"Establecer KPIs puede ser m\u00e1s complicado de lo que parece. En este art\u00edculo te explicamos 10 errores que no debes cometer.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-10-09T07:58:53+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:56:50+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/10\/blog-10-errores-kpis-eAlicia.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"520\" \/>\r\n\t<meta property=\"og:image:height\" content=\"272\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"Los errores m\u00e1s frecuentes de establecer KPI&#8217;s\",\"datePublished\":\"2020-10-09T07:58:53+00:00\",\"dateModified\":\"2023-06-06T14:56:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/\"},\"wordCount\":1407,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/linkedin-10-errores-kpis-eAlicia-1024x536.jpg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/\",\"name\":\"Los errores m\u00e1s frecuentes de establecer KPI's - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/linkedin-10-errores-kpis-eAlicia-1024x536.jpg\",\"datePublished\":\"2020-10-09T07:58:53+00:00\",\"dateModified\":\"2023-06-06T14:56:50+00:00\",\"description\":\"Establecer KPIs puede ser m\u00e1s complicado de lo que parece. En este art\u00edculo te explicamos 10 errores que no debes cometer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-errores-mas-frecuentes-de-establecer-kpis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los errores m\u00e1s frecuentes de establecer KPI&#8217;s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los errores m\u00e1s frecuentes de establecer KPI's - MST Holding Blog","description":"Establecer KPIs puede ser m\u00e1s complicado de lo que parece. En este art\u00edculo te explicamos 10 errores que no debes cometer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/","og_locale":"es_ES","og_type":"article","og_title":"Los errores m\u00e1s frecuentes de establecer KPI's - MST Holding Blog","og_description":"Establecer KPIs puede ser m\u00e1s complicado de lo que parece. En este art\u00edculo te explicamos 10 errores que no debes cometer.","og_url":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/","og_site_name":"MST Holding Blog","article_published_time":"2020-10-09T07:58:53+00:00","article_modified_time":"2023-06-06T14:56:50+00:00","og_image":[{"width":520,"height":272,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/10\/blog-10-errores-kpis-eAlicia.jpg","type":"image\/jpeg"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"Los errores m\u00e1s frecuentes de establecer KPI&#8217;s","datePublished":"2020-10-09T07:58:53+00:00","dateModified":"2023-06-06T14:56:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/"},"wordCount":1407,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/10\/linkedin-10-errores-kpis-eAlicia-1024x536.jpg","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/","url":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/","name":"Los errores m\u00e1s frecuentes de establecer KPI's - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2020\/10\/linkedin-10-errores-kpis-eAlicia-1024x536.jpg","datePublished":"2020-10-09T07:58:53+00:00","dateModified":"2023-06-06T14:56:50+00:00","description":"Establecer KPIs puede ser m\u00e1s complicado de lo que parece. En este art\u00edculo te explicamos 10 errores que no debes cometer.","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/los-errores-mas-frecuentes-de-establecer-kpis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Los errores m\u00e1s frecuentes de establecer KPI&#8217;s"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/1588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=1588"}],"version-history":[{"count":1,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/1588\/revisions"}],"predecessor-version":[{"id":3523,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/1588\/revisions\/3523"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=1588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=1588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=1588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}