{"id":2256,"date":"2021-11-17T09:57:51","date_gmt":"2021-11-17T08:57:51","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=2256"},"modified":"2023-06-06T16:55:44","modified_gmt":"2023-06-06T14:55:44","slug":"experiencia-del-cliente","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/","title":{"rendered":"La experiencia del cliente en Europa en 2022"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las marcas buscar\u00e1n que sus equipos de experiencia del cliente se adapten en 2022 a la \u00abnueva normalidad\u00bb a la hora de gestionar las nuevas expectativas y emociones de los clientes, centradas en temas como la aceleraci\u00f3n y la saturaci\u00f3n digital, la intimidad y la sostenibilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los clientes querr\u00e1n que m\u00e1s de la mitad de los servicios presentes en la \u00e9poca pand\u00e9mica se instalen en la \u00abnueva normalidad\u00bb y sean habituales. Por esto, es un error que las empresas y las instituciones hayan comenzado a reanudar algunas formas de negocio prepand\u00e9micas a medida que las restricciones se han ido eliminando.&nbsp;<strong>Los consumidores se han acostumbrado a muchos de los nuevos servicios, como las reuniones remotas y el pago digital<\/strong>&nbsp;ampliado, por lo que seguir\u00e1n dese\u00e1ndolos en el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un\u00a0<strong>estudio realizado por <a href=\"https:\/\/www.bigdata-social.com\/metodologia-forrester-wave\/\">Forrester<\/a><\/strong>\u00a0demuestra la consolidaci\u00f3n de\u00a0<strong>nuevos h\u00e1bitos de consumo y<\/strong>\u00a0<strong>la experiencia del cliente en 2022 depender\u00e1 de estos.<\/strong>\u00a0Por ejemplo, entre la mitad y dos tercios de los consumidores estadounidenses y europeos afirman que la pandemia ha cambiado la forma en la que compran productos. Adem\u00e1s, cada vez est\u00e1 cobrando m\u00e1s importancia la saturaci\u00f3n digital que est\u00e1n sufriendo los consumidores. Por ello, las empresas deben gestionar experiencias de clientes cada vez m\u00e1s h\u00edbridas mediante puntos de contacto f\u00edsicos y digitales. Conocer qu\u00e9 servicios conservar, ajustar o descartar determinar\u00e1 que marcas realicen con \u00e9xito la transici\u00f3n a la \u00abnueva normalidad\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La sostenibilidad y la privacidad, claves en 2022<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Uni\u00f3n Europea ha llevado a cabo en el \u00faltimo a\u00f1o pol\u00edticas para afrontar el cambio clim\u00e1tico. Esto ha llevado a proponer la estandarizaci\u00f3n y la obligatoriedad de los informes de sostenibilidad empresarial para m\u00e1s empresas a partir de 2023. Seg\u00fan el estudio de Forrester,\u00a0<strong>solo el 34% de los consumidores de la Uni\u00f3n Europea conf\u00eda en las empresas cuando dicen que se comprometen a reducir el cambio clim\u00e1tico<\/strong>,\u00a0<strong>siendo este un tema cada vez m\u00e1s importante para ellos<\/strong>. Como consecuencia, un 25% m\u00e1s de empresas de la UE, especialmente en los servicios financieros y en el comercio minorista, sumar\u00e1n directores de sostenibilidad en 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro aspecto que ser\u00e1 clave es la privacidad en las b\u00fasquedas del cliente. Un cuarto de los consumidores globales usan herramientas de privacidad y seguridad para evitar que las empresas rastreen su actividad en l\u00ednea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La depreciaci\u00f3n de los datos obligar\u00e1 a las empresas a recopilar m\u00e1s datos directamente de los clientes para\u00a0<a href=\"http:\/\/www.mstholding.com\"><strong>ofrecer experiencias individualizadas<\/strong>\u00a0en 2022<\/a>. De esta forma, los profesionales de CX de las empresas buscan reducir la dependencia de datos aportados por terceros. Por ello,<strong>\u00a0surge la necesidad de crear viajes digitales de privacidad o consentimiento pensando en el cliente<\/strong>, incluyendo indicadores clave de rendimiento y m\u00e9tricas relacionadas con la privacidad en sus programas de medici\u00f3n de CX para monitorear las b\u00fasquedas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las marcas buscar\u00e1n que sus equipos de experiencia del cliente se adapten en 2022 a la \u00abnueva normalidad\u00bb a la hora de gestionar las nuevas expectativas y emociones de los clientes, centradas en temas como la aceleraci\u00f3n y la saturaci\u00f3n digital, la intimidad y la sostenibilidad. Los clientes querr\u00e1n que m\u00e1s de la mitad de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-2256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>La experiencia del cliente en Europa en 2022 - MST Holding Blog<\/title>\r\n<meta name=\"description\" content=\"Las marcas buscar\u00e1n que sus equipos de experiencia del cliente se adapten en 2022 a la \u00abnueva normalidad\u00bb enfocada hacia el CX.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"La experiencia del cliente en Europa en 2022 - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"Las marcas buscar\u00e1n que sus equipos de experiencia del cliente se adapten en 2022 a la \u00abnueva normalidad\u00bb enfocada hacia el CX.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2021-11-17T08:57:51+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:55:44+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1263\" \/>\r\n\t<meta property=\"og:image:height\" content=\"827\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"La experiencia del cliente en Europa en 2022\",\"datePublished\":\"2021-11-17T08:57:51+00:00\",\"dateModified\":\"2023-06-06T14:55:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/\"},\"wordCount\":501,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/\",\"name\":\"La experiencia del cliente en Europa en 2022 - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png\",\"datePublished\":\"2021-11-17T08:57:51+00:00\",\"dateModified\":\"2023-06-06T14:55:44+00:00\",\"description\":\"Las marcas buscar\u00e1n que sus equipos de experiencia del cliente se adapten en 2022 a la \u00abnueva normalidad\u00bb enfocada hacia el CX.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png\",\"width\":1263,\"height\":827},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/experiencia-del-cliente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La experiencia del cliente en Europa en 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La experiencia del cliente en Europa en 2022 - MST Holding Blog","description":"Las marcas buscar\u00e1n que sus equipos de experiencia del cliente se adapten en 2022 a la \u00abnueva normalidad\u00bb enfocada hacia el CX.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/","og_locale":"es_ES","og_type":"article","og_title":"La experiencia del cliente en Europa en 2022 - MST Holding Blog","og_description":"Las marcas buscar\u00e1n que sus equipos de experiencia del cliente se adapten en 2022 a la \u00abnueva normalidad\u00bb enfocada hacia el CX.","og_url":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/","og_site_name":"MST Holding Blog","article_published_time":"2021-11-17T08:57:51+00:00","article_modified_time":"2023-06-06T14:55:44+00:00","og_image":[{"width":1263,"height":827,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png","type":"image\/png"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"La experiencia del cliente en Europa en 2022","datePublished":"2021-11-17T08:57:51+00:00","dateModified":"2023-06-06T14:55:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/"},"wordCount":501,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/","url":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/","name":"La experiencia del cliente en Europa en 2022 - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png","datePublished":"2021-11-17T08:57:51+00:00","dateModified":"2023-06-06T14:55:44+00:00","description":"Las marcas buscar\u00e1n que sus equipos de experiencia del cliente se adapten en 2022 a la \u00abnueva normalidad\u00bb enfocada hacia el CX.","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png","width":1263,"height":827},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/experiencia-del-cliente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La experiencia del cliente en Europa en 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/UUUUUUUUUUUUUUUUUUUUUUUUUUUUU.png","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=2256"}],"version-history":[{"count":1,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2256\/revisions"}],"predecessor-version":[{"id":2259,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2256\/revisions\/2259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/2258"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=2256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=2256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=2256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}