{"id":2272,"date":"2021-11-30T11:06:02","date_gmt":"2021-11-30T10:06:02","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=2272"},"modified":"2023-06-06T16:55:44","modified_gmt":"2023-06-06T14:55:44","slug":"exporc21-mstholding","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/","title":{"rendered":"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La<strong> Feria Expo Relaci\u00f3n Cliente 2021<\/strong>, un referente para todos los profesionales de la relaci\u00f3n con el cliente y el contact center, ha regresado a su formato presencial y lo ha hecho por todo lo alto, invitando a los asistentes a vivir una experiencia de cine en las salas Kin\u00e9polis de Ciudad de la Imagen (Madrid).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un a\u00f1o m\u00e1s <strong><a href=\"http:\/\/www.mstholding.com\">MST HOLDING<\/a><\/strong> ha participado en este destacado evento dentro del sector contact center, que ha regresado a su cita presencial y ha acogido a todos aquellos que desean estar al tanto de los nuevos modelos de comunicaci\u00f3n y las mejores f\u00f3rmulas para optimizar la relaci\u00f3n con el cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los temas m\u00e1s abordados este a\u00f1o ha sido c\u00f3mo la pandemia ha propiciado un cambio real en el rol del contact center dentro de cualquier organizaci\u00f3n, ocupando una posici\u00f3n m\u00e1s estrat\u00e9gica. Al mismo tiempo, se han planteado cuestiones entre las que figuran c\u00f3mo mantener esa posici\u00f3n o qu\u00e9 responsabilidad tienen los l\u00edderes del CC para seguir demostrando el valor que aporta la funci\u00f3n de atenci\u00f3n al cliente a la compa\u00f1\u00eda. Y no menos importantes son otros puntos sobre los que tambi\u00e9n se ha hablado mucho como cu\u00e1les son los ejes sobre los que seguir trabajando para mantener al CAC en primera l\u00ednea, entre los que se hallan mensajer\u00eda en tiempo real, autoservicio, IA, cloud o la importancia del equipo humano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mi\u00e9rcoles 24 de noviembre, se celebr\u00f3 la Gala de entrega de los Premios Excelencia Relaci\u00f3n con Clientes. Unos galardones organizados por la AEERC (Asociaci\u00f3n Espa\u00f1ola de Expertos en Relaci\u00f3n con Clientes), con la colaboraci\u00f3n de IFAES y bajo la metodolog\u00eda y el estudio t\u00e9cnico de IZO, que reunieron a m\u00e1s de 400 profesionales de empresas, proveedores y compa\u00f1\u00edas tecnol\u00f3gicas con foco en ofrecer un servicio excelente a sus clientes en todos los canales de contacto y con foco en generarles experiencias diferenciadoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta edici\u00f3n se han realizado 41 auditor\u00edas con un total de 656 horas en 12 ciudades diferentes realizadas en dos modalidades: telem\u00e1tica y presencial; se han auditado 840 puntos de control validados en cada auditor\u00eda; se han enviado m\u00e1s de 80.000 encuestas a clientes finales y evaluado 7.200 puestos de operaci\u00f3n en los Centros de Relaci\u00f3n con Clientes entre Proveedores y Empresas Cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde MST Holding queremos agradecer al evento esta oportunidad de reconocimiento a las empresas del sector del Contact Center y el compromiso y el apoyo a la \u201cEXCELENCIA en el Servicio al Cliente\u201d. Gracias a la Feria Relaci\u00f3n Cliente por impulsar y dar visibilidad a la importante actividad que realiza el sector de la Relaci\u00f3n con Clientes.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>\u201c<em>Es tiempo de agradecimiento y, sin duda, tiempo de reinventarse, de innovar, de adaptarse, de ser nuestra mejor versi\u00f3n, de aprender y ser, ahora m\u00e1s que nunca, excelentes<\/em>\u201d.<\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.mstholding.com\">www.mstholding.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Feria Expo Relaci\u00f3n Cliente 2021, un referente para todos los profesionales de la relaci\u00f3n con el cliente y el contact center, ha regresado a su formato presencial y lo ha hecho por todo lo alto, invitando a los asistentes a vivir una experiencia de cine en las salas Kin\u00e9polis de Ciudad de la Imagen [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[265],"class_list":["post-2272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-exporc21"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula - MST Holding Blog<\/title>\r\n<meta name=\"description\" content=\"La Feria Expo Relaci\u00f3n Cliente 2021, un referente para todos los profesionales de la relaci\u00f3n con el cliente y el contact center.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"La Feria Expo Relaci\u00f3n Cliente 2021, un referente para todos los profesionales de la relaci\u00f3n con el cliente y el contact center.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2021-11-30T10:06:02+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:55:44+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/ok-para-blog-feria-pelicula.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1236\" \/>\r\n\t<meta property=\"og:image:height\" content=\"819\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula\",\"datePublished\":\"2021-11-30T10:06:02+00:00\",\"dateModified\":\"2023-06-06T14:55:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/\"},\"wordCount\":516,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ok-para-blog-feria-pelicula.png\",\"keywords\":[\"Exporc21\"],\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/\",\"name\":\"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ok-para-blog-feria-pelicula.png\",\"datePublished\":\"2021-11-30T10:06:02+00:00\",\"dateModified\":\"2023-06-06T14:55:44+00:00\",\"description\":\"La Feria Expo Relaci\u00f3n Cliente 2021, un referente para todos los profesionales de la relaci\u00f3n con el cliente y el contact center.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ok-para-blog-feria-pelicula.png\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ok-para-blog-feria-pelicula.png\",\"width\":1236,\"height\":819},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/exporc21-mstholding\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula - MST Holding Blog","description":"La Feria Expo Relaci\u00f3n Cliente 2021, un referente para todos los profesionales de la relaci\u00f3n con el cliente y el contact center.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/","og_locale":"es_ES","og_type":"article","og_title":"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula - MST Holding Blog","og_description":"La Feria Expo Relaci\u00f3n Cliente 2021, un referente para todos los profesionales de la relaci\u00f3n con el cliente y el contact center.","og_url":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/","og_site_name":"MST Holding Blog","article_published_time":"2021-11-30T10:06:02+00:00","article_modified_time":"2023-06-06T14:55:44+00:00","og_image":[{"width":1236,"height":819,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/ok-para-blog-feria-pelicula.png","type":"image\/png"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula","datePublished":"2021-11-30T10:06:02+00:00","dateModified":"2023-06-06T14:55:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/"},"wordCount":516,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/ok-para-blog-feria-pelicula.png","keywords":["Exporc21"],"articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/","url":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/","name":"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/ok-para-blog-feria-pelicula.png","datePublished":"2021-11-30T10:06:02+00:00","dateModified":"2023-06-06T14:55:44+00:00","description":"La Feria Expo Relaci\u00f3n Cliente 2021, un referente para todos los profesionales de la relaci\u00f3n con el cliente y el contact center.","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/ok-para-blog-feria-pelicula.png","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/ok-para-blog-feria-pelicula.png","width":1236,"height":819},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/exporc21-mstholding\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Un a\u00f1o m\u00e1s #EXPORC2021 nos ha brindado una experiencia de pel\u00edcula"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2021\/11\/ok-para-blog-feria-pelicula.png","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=2272"}],"version-history":[{"count":1,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2272\/revisions"}],"predecessor-version":[{"id":2276,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2272\/revisions\/2276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/2275"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=2272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=2272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=2272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}