{"id":2366,"date":"2022-03-09T10:32:46","date_gmt":"2022-03-09T09:32:46","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=2366"},"modified":"2023-06-06T16:55:08","modified_gmt":"2023-06-06T14:55:08","slug":"las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/","title":{"rendered":"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La experiencia demuestra que&nbsp;<strong>la buena relaci\u00f3n entre cliente y empresa no siempre es duradera<\/strong>, ya que pueden tener lugar incidencias que la debiliten e incluso que terminen por romperla, y las quejas forman parte de este sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cuando se produce una queja de un cliente, se da una situaci\u00f3n que requiere de un trato delicado<\/strong>, de manera que sirva para aportar una soluci\u00f3n al cliente que no termine con la p\u00e9rdida del mismo, o peor, con el efecto \u201cboca a boca\u201d y la p\u00e9rdida de prestigio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El trato que se d\u00e9 de las quejas desde los centros de atenci\u00f3n al cliente, va a ser fundamental para que \u00e9sta sirva como precedente de fidelizaci\u00f3n de un cliente<\/strong>, o la p\u00e9rdida de valor de la empresa frente a futuros clientes y\/o en el mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nunca hay que perder el punto de vista, de que un cliente es un ser humano<\/strong>&nbsp;y, por tanto, cuando nos enfrentemos ante una queja se debe considerar la propia naturaleza humana. Es decir,&nbsp;<strong>necesitan sentir que son escuchados, y que se valoran sus opiniones, preocupaciones o dudas, d\u00e1ndoles su merecido reconocimiento<\/strong>. Para ello, el personal responsable de gestionar este tipo de incidencias, debe tener grandes dosis de tacto, flexibilidad y reflexi\u00f3n para que, de esta manera, consigamos que el cliente llegue a olvidar que ha tenido lugar tal insatisfacci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer punto esencial y b\u00e1sico a considerar por la empresa para la correcta gesti\u00f3n de las quejas, es el de&nbsp;<strong>facilitar canales de contacto para que el cliente reporte las incidencias<\/strong>. Esto nos servir\u00e1 como oportunidad de mejora, tanto de servicios como de productos, realizando campa\u00f1as de marketing exitosas:&nbsp;<strong>tanto tel\u00e9fono como email de atenci\u00f3n al cliente debe quedar claramente reflejado en todas las comunicaciones comerciales<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Conectar con el cliente<\/strong>: previo a la conversaci\u00f3n con el cliente, es preciso planificar las herramientas que se van a utilizar. Es decir, qu\u00e9 palabras utilizaremos para que el cliente sienta que el agente le escucha y comprende y adem\u00e1s, que valora sus preocupaciones, y que empatiza con \u00e9l.<\/li><li><strong>Entender el problema y plantear soluciones<\/strong>: ante las quejas de clientes, la formaci\u00f3n continua del personal encargado de tratarlas es muy importante. Esto es, los empleados deben disponer de todos los recursos disponibles para poder aportar variedad de soluciones a los clientes, d\u00e1ndoles as\u00ed, la opci\u00f3n de elegir la que m\u00e1s se ajuste a sus necesidades. S\u00f3lo as\u00ed, evitamos el deterioro de la imagen de la empresa. Nunca debe cerrarse una conversaci\u00f3n sin que la queja haya sido solucionada.<\/li><li><strong>Compensaci\u00f3n por las molestias<\/strong>: en su mayor parte, el cliente que efect\u00faa una queja espera una compensaci\u00f3n por las molestias ocasionadas. Pero adem\u00e1s, en la realidad es la mejor manera para solventar las incidencias que tienen lugar debido a quejas. Esto es, la insatisfacci\u00f3n que ha dado lugar a la queja, debe transformarse en una soluci\u00f3n con la que el cliente sale ganando, sorprendi\u00e9ndolo con una respuesta inesperada y favorable a sus intereses y necesidades. Existen variedad de opciones a la hora de conseguir este objetivo las cuales tambi\u00e9n dependen del sector de la organizaci\u00f3n, y del tipo de cliente. Por lo general, se mandan por email o sms, y a tiempo real, tarjetas regalo, vales de descuento, entradas de cine, ofertas exclusivas, etc. Resumiendo, hay que compensar al cliente, con obsequios que puedan satisfacerlo, puesto que afianzarlo es tan importante como agradecerle que ayude a mejorar la organizaci\u00f3n.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A modo de conclusi\u00f3n, podemos extraer que la resoluci\u00f3n de las peticiones, quejas, reclamos y sugerencias, tambi\u00e9n forma parte de la confianza que da una empresa, y no s\u00f3lo a trav\u00e9s de buenas experiencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En definitiva, el centro de atenci\u00f3n al cliente ser\u00e1 capaz de transformar la mayor\u00eda de las quejas de clientes en oportunidades de mejora, facilitando la fidelizaci\u00f3n de contactos considerados dif\u00edciles a trav\u00e9s de la creaci\u00f3n de lazos de confianza hacia la empresa, entre el agente y el cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.mstholding.com\">www.mstholding.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La experiencia demuestra que&nbsp;la buena relaci\u00f3n entre cliente y empresa no siempre es duradera, ya que pueden tener lugar incidencias que la debiliten e incluso que terminen por romperla, y las quejas forman parte de este sistema. Cuando se produce una queja de un cliente, se da una situaci\u00f3n que requiere de un trato delicado, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-2366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho - MST Holding Blog<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"La experiencia demuestra que&nbsp;la buena relaci\u00f3n entre cliente y empresa no siempre es duradera, ya que pueden tener lugar incidencias que la debiliten e incluso que terminen por romperla, y las quejas forman parte de este sistema. Cuando se produce una queja de un cliente, se da una situaci\u00f3n que requiere de un trato delicado, [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-03-09T09:32:46+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:55:08+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/03\/ttttttttttttttt.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1068\" \/>\r\n\t<meta property=\"og:image:height\" content=\"709\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho\",\"datePublished\":\"2022-03-09T09:32:46+00:00\",\"dateModified\":\"2023-06-06T14:55:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/\"},\"wordCount\":717,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ttttttttttttttt.png\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/\",\"name\":\"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ttttttttttttttt.png\",\"datePublished\":\"2022-03-09T09:32:46+00:00\",\"dateModified\":\"2023-06-06T14:55:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ttttttttttttttt.png\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ttttttttttttttt.png\",\"width\":1068,\"height\":709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho - MST Holding Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/","og_locale":"es_ES","og_type":"article","og_title":"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho - MST Holding Blog","og_description":"La experiencia demuestra que&nbsp;la buena relaci\u00f3n entre cliente y empresa no siempre es duradera, ya que pueden tener lugar incidencias que la debiliten e incluso que terminen por romperla, y las quejas forman parte de este sistema. Cuando se produce una queja de un cliente, se da una situaci\u00f3n que requiere de un trato delicado, [&hellip;]","og_url":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/","og_site_name":"MST Holding Blog","article_published_time":"2022-03-09T09:32:46+00:00","article_modified_time":"2023-06-06T14:55:08+00:00","og_image":[{"width":1068,"height":709,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/03\/ttttttttttttttt.png","type":"image\/png"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho","datePublished":"2022-03-09T09:32:46+00:00","dateModified":"2023-06-06T14:55:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/"},"wordCount":717,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/03\/ttttttttttttttt.png","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/","url":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/","name":"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/03\/ttttttttttttttt.png","datePublished":"2022-03-09T09:32:46+00:00","dateModified":"2023-06-06T14:55:08+00:00","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/03\/ttttttttttttttt.png","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/03\/ttttttttttttttt.png","width":1068,"height":709},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/las-quejas-y-como-transformarlas-en-tu-aliada-para-crear-un-cliente-satisfecho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Las quejas y c\u00f3mo transformarlas en tu aliada para crear un cliente satisfecho"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/03\/ttttttttttttttt.png","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=2366"}],"version-history":[{"count":1,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2366\/revisions"}],"predecessor-version":[{"id":2369,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2366\/revisions\/2369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/2368"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=2366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=2366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=2366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}