{"id":2668,"date":"2022-05-17T11:53:14","date_gmt":"2022-05-17T09:53:14","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=2668"},"modified":"2023-06-06T16:54:15","modified_gmt":"2023-06-06T14:54:15","slug":"outsourcing-servicios","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/","title":{"rendered":"Outsourcing con MST HOLDING"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Externalizar servicios<\/strong>&nbsp;es una de las alternativas de gesti\u00f3n m\u00e1s implementadas en ciertos sectores de los negocios, especialmente cuando una empresa no cuenta con los medios ni los recursos suficientes para llevar a cabo una serie de tareas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 significa externalizar<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En un negocio,&nbsp;<strong>externalizar servicios es contratarlos de otra empresa o de un trabajador independiente<\/strong>, ya sea a nivel nacional o internacional, acordando que se ocupe de gestionar determinadas actividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El outsourcing, que es como tambi\u00e9n se denomina a esta pr\u00e1ctica empresarial no es una opci\u00f3n reservada a las grandes corporaciones<\/strong>. De hecho, es com\u00fan que las peque\u00f1as y medianas recurran al&nbsp;<em>Business Process Outsourcing<\/em>&nbsp;(BPO o externalizaci\u00f3n) para obtener servicios y habilidades que generalmente les resultar\u00edan dif\u00edciles de desarrollar, debido a restricciones financieras o de mano de obra, o posiblemente una combinaci\u00f3n de ambas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Al externalizar servicios es m\u00e1s sencillo hacer crecer el negocio cuando se necesita y sin grandes inversiones<\/strong>; al mismo tiempo que se aumenta la eficiencia en los procesos y se ahorra bastante dinero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La subcontrataci\u00f3n tambi\u00e9n permite a las empresas centrarse en otros asuntos de negocio, mientras los expertos externos se ocupan de los detalles. Un ejemplo perfecto ser\u00eda saber que el telemarketing es la mejor manera de promocionar un nuevo producto o servicio que se va a lanzar, ya sea a nivel local, nacional o internacional; pero admitir que no es realmente el fuerte de la empresa y optar por contratar una empresa de outsourcing que brinde estos servicios, mientras el negocio se concentra en prepararse para la afluencia de consultas como resultado de la campa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El outsourcing llega a funciones tan dispares como la contabilidad, las ventas, el dise\u00f1o y fabricaci\u00f3n, la asistencia administrativa, el cumplimiento normativo, o el servicio al cliente, entre otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La compa\u00f1\u00eda especializada que se ocupa del trabajo subcontratado a menudo se simplifica y normalmente tendr\u00e1&nbsp;<strong>capacidades mejoradas y acceso a nuevas tecnolog\u00edas<\/strong>; en las que una compa\u00f1\u00eda en crecimiento no podr\u00eda permitirse invertir por su cuenta. Adem\u00e1s, si una empresa busca expandirse, la subcontrataci\u00f3n tambi\u00e9n es una forma rentable de comenzar a construir bases en otros pa\u00edses.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por todo esto, la externalizaci\u00f3n de servicio con MST Holding te permite:<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Obtener Informaci\u00f3n en tiempo real:<em> <\/em><\/strong>Servicios integrados en nuestro sistema CTI. Esto nos permite extraer toda la informaci\u00f3n necesaria para la correcta gesti\u00f3n del servicio:<ul><li>Mejor dimensionamiento basado en las necesidades reales del servicio.<\/li><\/ul><ul><li>Control de la productividad de los agentes.<\/li><\/ul><ul><li>Informes completos sobre la actividad del servicio.<\/li><\/ul><ul><li>Evoluci\u00f3n hist\u00f3rica del servicio por fechas.<\/li><\/ul><\/li><li><strong>MST trabaja para mejorar tus costes:<\/strong><ul><li>Por una mayor productividad de los agentes: perfil adecuado al servicio, proactividad, alta formaci\u00f3n.<\/li><\/ul><ul><li>Redimensionamiento del servicio, en funci\u00f3n del comportamiento real diario y por franja horaria de atenci\u00f3n.<\/li><\/ul><ul><li>Automatizaci\u00f3n de los procesos.<\/li><\/ul><ul><li>Alto porcentaje de resoluci\u00f3n en primera llamada.<\/li><\/ul><ul><li>Aplicativos especializados para cada servicio: reconocimiento del cliente, seguimiento online, informes autom\u00e1ticos por clientes, modelos, gama de productos, zonas geogr\u00e1ficas, gesti\u00f3n de RMA\u2019s, etc.<\/li><\/ul><ul><li>En todos los servicios est\u00e1 la figura del Responsable de procedimientos y formaci\u00f3n para la mejora continua del servicio y aumento de la productividad.<\/li><\/ul><\/li><li><strong>Flexibilidad: <\/strong>Capacidad de crecimiento y costes variables. Adem\u00e1s de que los costes son variables, a trav\u00e9s del an\u00e1lisis de llamadas se puede obtener un hist\u00f3rico, para prever necesidades puntuales o estaci\u00f3nales de personal, y dimensionando adecuadamente.<\/li><li><strong>Aumento de ventas: <\/strong>Suavizamos el coste de oportunidad al incrementar la productividad (mayor n\u00famero de llamadas gestionadas por agente), evitamos los costes de oportunidad de \u00abno haber gestionado una posible llamada que genera negocio\u00bb. A m\u00e1s llamadas con los mismos recursos, m\u00e1s posibilidades de ventas.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Mejor eficiencia: <\/strong>MST trabaja siempre con los mejores proveedores y, mediante su empresa RunCall System siempre est\u00e1 innovando para mejorar la calidad del servicio. As\u00ed se detectan las necesidades, tanto a nivel de telefon\u00eda, como desde el punto de vista del aplicativo inform\u00e1tico para gestionar las llamadas e incidencias, con el objetivo de reducir tanto el tiempo de llamada, como la gesti\u00f3n administrativa que tiene relaci\u00f3n directa con cada llamada, evitando la cola de espera por parte del cliente, y ofreciendo la m\u00e1xima informaci\u00f3n in situ en cada llamada.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Te ahorramos costes de infraestructura: <\/strong>No es necesario habilitar un espacio con su infraestructura en las oficinas del cliente, MST ya lo tiene y, adem\u00e1s, con la mejor tecnolog\u00eda para Call Center.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Somos m\u00e1s productivos: <\/strong>A trav\u00e9s del an\u00e1lisis de los informes del CTI podemos dimensionar adecuadamente al personal, realizando un estudio por tipolog\u00eda de llamadas, y analizando qu\u00e9 productividad \u00f3ptima puede alcanzar el agente telef\u00f3nico, orientando todos los recursos a conseguir esta productividad \u00f3ptima.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Gestionamos mejor los recursos:<\/strong> Automatizaci\u00f3n de establecimiento de turnos y calendarios, control de las bajas y su sustituci\u00f3n y una mejor gesti\u00f3n de las horas punta y colas.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>MST <\/strong>cuenta con un sistema de back ups de personal que nos permite cubrir las bajas, vacaciones y puntas de servicio.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Nuestros centros est\u00e1n abiertos 24h: <\/strong>Mayor flexibilidad del servicio. Nuestras instalaciones est\u00e1n abiertas <strong>24h\/7<\/strong> d\u00edas al a\u00f1o.<strong> <\/strong>MST<strong> <\/strong>tiene servicios 24\/7, lo que permite poder dar servicios con amplitud de horarios.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>La satisfacci\u00f3n de tus clientes es nuestro objetivo: <\/strong>A trav\u00e9s de los controles de calidad se establecen las bases que permitan una mayor homogeneidad en el trato por parte de los agentes telef\u00f3nicos que componen esta primera l\u00ednea, transmitiendo todos ellos de la misma forma la imagen corporativa de la compa\u00f1\u00eda, reduciendo la dispersi\u00f3n de los agentes a nivel de calidad en atenci\u00f3n telef\u00f3nica.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Nuestra tecnolog\u00eda:<\/strong> La tecnolog\u00eda del MST permite un control on-line del servicio por parte de nuestros clientes en cada minuto y momento. Desde cualquier parte del mundo cualquier manager sabe lo que est\u00e1 pasando en su servicio de Customer Service.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes encontrar m\u00e1s informaci\u00f3n sobre nuestros servicios en <a href=\"http:\/\/www.mstholding.com\">www.mstholding.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Externalizar servicios&nbsp;es una de las alternativas de gesti\u00f3n m\u00e1s implementadas en ciertos sectores de los negocios, especialmente cuando una empresa no cuenta con los medios ni los recursos suficientes para llevar a cabo una serie de tareas. Qu\u00e9 significa externalizar En un negocio,&nbsp;externalizar servicios es contratarlos de otra empresa o de un trabajador independiente, ya [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-2668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Outsourcing con MST HOLDING - MST Holding Blog<\/title>\r\n<meta name=\"description\" content=\"Externalizar servicios\u00a0es una de las alternativas de gesti\u00f3n m\u00e1s implementadas en ciertos sectores de los negocios\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Outsourcing con MST HOLDING - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"Externalizar servicios\u00a0es una de las alternativas de gesti\u00f3n m\u00e1s implementadas en ciertos sectores de los negocios\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-05-17T09:53:14+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:54:15+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/222222222222.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1234\" \/>\r\n\t<meta property=\"og:image:height\" content=\"821\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"Outsourcing con MST HOLDING\",\"datePublished\":\"2022-05-17T09:53:14+00:00\",\"dateModified\":\"2023-06-06T14:54:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/\"},\"wordCount\":1040,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/222222222222.png\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/\",\"name\":\"Outsourcing con MST HOLDING - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/222222222222.png\",\"datePublished\":\"2022-05-17T09:53:14+00:00\",\"dateModified\":\"2023-06-06T14:54:15+00:00\",\"description\":\"Externalizar servicios\u00a0es una de las alternativas de gesti\u00f3n m\u00e1s implementadas en ciertos sectores de los negocios\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/222222222222.png\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/222222222222.png\",\"width\":1234,\"height\":821},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/outsourcing-servicios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Outsourcing con MST HOLDING\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Outsourcing con MST HOLDING - MST Holding Blog","description":"Externalizar servicios\u00a0es una de las alternativas de gesti\u00f3n m\u00e1s implementadas en ciertos sectores de los negocios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/","og_locale":"es_ES","og_type":"article","og_title":"Outsourcing con MST HOLDING - MST Holding Blog","og_description":"Externalizar servicios\u00a0es una de las alternativas de gesti\u00f3n m\u00e1s implementadas en ciertos sectores de los negocios","og_url":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/","og_site_name":"MST Holding Blog","article_published_time":"2022-05-17T09:53:14+00:00","article_modified_time":"2023-06-06T14:54:15+00:00","og_image":[{"width":1234,"height":821,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/222222222222.png","type":"image\/png"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"Outsourcing con MST HOLDING","datePublished":"2022-05-17T09:53:14+00:00","dateModified":"2023-06-06T14:54:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/"},"wordCount":1040,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/222222222222.png","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/","url":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/","name":"Outsourcing con MST HOLDING - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/222222222222.png","datePublished":"2022-05-17T09:53:14+00:00","dateModified":"2023-06-06T14:54:15+00:00","description":"Externalizar servicios\u00a0es una de las alternativas de gesti\u00f3n m\u00e1s implementadas en ciertos sectores de los negocios","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/222222222222.png","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/222222222222.png","width":1234,"height":821},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/outsourcing-servicios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Outsourcing con MST HOLDING"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/222222222222.png","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=2668"}],"version-history":[{"count":4,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2668\/revisions"}],"predecessor-version":[{"id":2674,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2668\/revisions\/2674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/2670"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=2668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=2668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=2668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}