{"id":2681,"date":"2022-05-24T09:47:28","date_gmt":"2022-05-24T07:47:28","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=2681"},"modified":"2023-06-06T16:53:32","modified_gmt":"2023-06-06T14:53:32","slug":"principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/","title":{"rendered":"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><em>El canal telef\u00f3nico sigue siendo el m\u00e1s utilizado y el m\u00e1s importante en la atenci\u00f3n al cliente y el que m\u00e1s ha evolucionado gracias al mundo digital<\/em>.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan los datos de uno de los m\u00e1s recientes estudios sobre el&nbsp;<em>contact center<\/em>&nbsp;de la Asociaci\u00f3n CEX en 2021, el tel\u00e9fono con sus m\u00e1s de 100 a\u00f1os de edad sigue siendo el principal medio de contacto (78%) en la atenci\u00f3n al cliente. A gran distancia est\u00e1 el segundo, el correo electr\u00f3nico, con un 12%, y el tercero, los&nbsp;<em>chat<\/em>&nbsp;o&nbsp;<em>bots<\/em>, con un 4%. Es, por tanto, el canal en el que las empresas siguen enfocando o, al menos, deber\u00edan hacerlo, sus esfuerzos a la hora de mejorar su atenci\u00f3n al cliente. Es evidente que los clientes exigen un trato particular, cercano y de persona a persona antes que con una m\u00e1quina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pregunta es: \u00bfY c\u00f3mo se hace esto en la \u00e9poca digital y los datos? Pues, curiosamente, es tambi\u00e9n el tel\u00e9fono el canal que m\u00e1s ha evolucionado y mejor se ha adaptado a los nuevos tiempos, gracias a la telefon\u00eda digital. Este cambio ha hecho dar un salto de gigante a la comunicaci\u00f3n de voz, manteniendo su caracter\u00edstica b\u00e1sica principal, el contacto de humano a humano, pero aprovechando la multitud de nuevas posibilidades que da la era digital.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El medio que rompe las limitaciones de la oficina<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El primer cambio, y que se ha notado en la pandemia con la proliferaci\u00f3n del teletrabajo, es que la telefon\u00eda ya no estaba ligada a una oficina f\u00edsica. Es posible llevarse el trabajo a cualquier parte, incluyendo particularmente las funciones del&nbsp;<em>call center<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cambio viene dado con el traslado de la comunicaci\u00f3n de voz mediante una centralita anal\u00f3gica a una digital. Esto hace que s\u00f3lo se necesite un ordenador o dispositivo conectado a Internet para poder desviar y gestionar cualquier llamada al n\u00famero de la empresa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ahorro de costes, optimizaci\u00f3n y flexibilidad<\/strong><strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Estos beneficios se derivan de lo anteriormente comentado. Sin unas \u2018paredes\u2019 que limiten el n\u00famero de usuarios es posible contar con equipos flexibles, a los que es tremendamente sencillo \u2013bastan unos minutos para montar las extensiones y empezar a funcionar\u2013 ampliar o reducir sus efectivos. Esto se traduce en que una empresa puede planificar al mil\u00edmetro sus costes en personal anuales, preparando aquellas \u00e9pocas cuando necesite m\u00e1s o menos agentes atendiendo a los clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, la telefon\u00eda en la nube o telefon\u00eda IP, como tambi\u00e9n se la llama, rompen la necesidad de estar vinculado a una l\u00ednea fija de un operador. S\u00f3lo necesitamos un proveedor de Internet que nos d\u00e9 el suficiente ancho de banda y podemos buscar un servicio de centralita virtual, que los hay desde gratuitos a casi cualquier coste, que nos permitir\u00e1 tener todos los n\u00fameros de tel\u00e9fono que queramos, migrar el que ten\u00edamos en la oficina y tantas extensiones como queramos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Presencia 24\/7 m\u00e1s all\u00e1&nbsp;del contestador<\/strong><strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Avanzando en los cambios de la telefon\u00eda digital que mantienen el canal a la vanguardia para la atenci\u00f3n a clientes est\u00e1 la posibilidad que dan estos sistemas de contar con una presencia inteligente, incluso cuando no hay operador. No es un simple contestador en el que alguien tiene que escuchar los mensajes al volver a la oficina, ahora es posible dirigir a los clientes mediante men\u00fas de voz hasta cada uno de los responsables y que estos reciban esos&nbsp;<em>leads<\/em>&nbsp;para cuando vuelvan a estar disponibles, permitiendo una mejora considerable de la satisfacci\u00f3n, porque reciben soluciones a sus quejas o del aprovechamiento de oportunidades de venta por parte de la empresa ya que ning\u00fan interesado se queda sin contactar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>An\u00e1lisis de lo que dicen los clientes y operadores<\/strong><strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1s es el avance m\u00e1s importante y, por otra parte, reciente de la telefon\u00eda digital. Era su tal\u00f3n de Aquiles frente al correo electr\u00f3nico, los&nbsp;<em>chatbots<\/em>, ya que \u00bfc\u00f3mo se puede combinar algo tan ef\u00edmero como una llamada con el an\u00e1lisis de todo lo que se dice en ella? La soluci\u00f3n de la grabaci\u00f3n solo era una parte hasta que ha llegado la transcripci\u00f3n autom\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las centralitas virtuales m\u00e1s avanzadas cuentan con esta caracter\u00edstica que transforma en texto cualquier conversaci\u00f3n telef\u00f3nica y permite, por tanto, analizar en tiempo real qu\u00e9 es lo que se est\u00e1 diciendo en ellas. Las aplicaciones son infinitas ya que se puede saber qu\u00e9 productos son los que reciben m\u00e1s quejas, cu\u00e1les son los m\u00e1s consultados&nbsp;<em>vs<\/em>. los que m\u00e1s se promociona o, incluso, de entre los agentes o vendedores que mejor lo hacen, descubrir el \u2018por qu\u00e9\u2019 y compartir el conocimiento con el resto del equipo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Una transici\u00f3n transparente, sencilla y barata<\/strong><strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las ventajas y aplicaciones de la telefon\u00eda digital son enormes, pero lo que se mantiene es el miedo de muchas empresas a dar el salto. En primer lugar, porque temen perder el n\u00famero \u2018de toda la vida\u2019, algo que es infundado dado que no s\u00f3lo podr\u00edan migrarlo a la nube sino contar con muchos otros m\u00e1s para, por ejemplo, dar servicio en el extranjero sin necesidad de tener una oficina y una l\u00ednea de tel\u00e9fono all\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, tambi\u00e9n es habitual el miedo a salir de la zona de confort. \u00bfPuede sobrevivir una empresa con un sistema de telefon\u00eda anal\u00f3gico? Es cuestionable, pero lo que s\u00ed es una realidad es que nunca podr\u00e1 hacer crecer su negocio adecuadamente y se perder\u00e1 numerosas oportunidades que ahora mismo se le cuelan entre los dedos mientras alguien corre a descolgar el auricular en una mesa. Y la realidad es que ni siquiera son necesarios unos conocimientos t\u00e9cnicos avanzados porque cualquier proveedor nos ofrecer\u00e1, como hemos indicado, todas las facilidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En definitiva, ni es caro, ni complicado ni nos llevar\u00e1 mucho tiempo no s\u00f3lo aprovechar las capacidades del principal canal de atenci\u00f3n al cliente en 2022, sino de adaptarlo y adecuarlo a los tiempos que corren con todas las posibilidades que ofrece el mundo digital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.mstholding.com\">www.mstholding.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El canal telef\u00f3nico sigue siendo el m\u00e1s utilizado y el m\u00e1s importante en la atenci\u00f3n al cliente y el que m\u00e1s ha evolucionado gracias al mundo digital. Seg\u00fan los datos de uno de los m\u00e1s recientes estudios sobre el&nbsp;contact center&nbsp;de la Asociaci\u00f3n CEX en 2021, el tel\u00e9fono con sus m\u00e1s de 100 a\u00f1os de edad [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-2681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero - MST Holding Blog<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"El canal telef\u00f3nico sigue siendo el m\u00e1s utilizado y el m\u00e1s importante en la atenci\u00f3n al cliente y el que m\u00e1s ha evolucionado gracias al mundo digital. Seg\u00fan los datos de uno de los m\u00e1s recientes estudios sobre el&nbsp;contact center&nbsp;de la Asociaci\u00f3n CEX en 2021, el tel\u00e9fono con sus m\u00e1s de 100 a\u00f1os de edad [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-05-24T07:47:28+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:53:32+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/4444.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1235\" \/>\r\n\t<meta property=\"og:image:height\" content=\"823\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero\",\"datePublished\":\"2022-05-24T07:47:28+00:00\",\"dateModified\":\"2023-06-06T14:53:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/\"},\"wordCount\":1084,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/4444.png\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/\",\"name\":\"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/4444.png\",\"datePublished\":\"2022-05-24T07:47:28+00:00\",\"dateModified\":\"2023-06-06T14:53:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/4444.png\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/4444.png\",\"width\":1235,\"height\":823},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero - MST Holding Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/","og_locale":"es_ES","og_type":"article","og_title":"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero - MST Holding Blog","og_description":"El canal telef\u00f3nico sigue siendo el m\u00e1s utilizado y el m\u00e1s importante en la atenci\u00f3n al cliente y el que m\u00e1s ha evolucionado gracias al mundo digital. Seg\u00fan los datos de uno de los m\u00e1s recientes estudios sobre el&nbsp;contact center&nbsp;de la Asociaci\u00f3n CEX en 2021, el tel\u00e9fono con sus m\u00e1s de 100 a\u00f1os de edad [&hellip;]","og_url":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/","og_site_name":"MST Holding Blog","article_published_time":"2022-05-24T07:47:28+00:00","article_modified_time":"2023-06-06T14:53:32+00:00","og_image":[{"width":1235,"height":823,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/4444.png","type":"image\/png"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero","datePublished":"2022-05-24T07:47:28+00:00","dateModified":"2023-06-06T14:53:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/"},"wordCount":1084,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/4444.png","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/","url":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/","name":"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/4444.png","datePublished":"2022-05-24T07:47:28+00:00","dateModified":"2023-06-06T14:53:32+00:00","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/4444.png","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/4444.png","width":1235,"height":823},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/principales-canales-de-atencion-al-cliente-2022-el-telefono-sigue-el-primero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Principales canales de atenci\u00f3n al cliente 2022: el tel\u00e9fono sigue el primero"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/05\/4444.png","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=2681"}],"version-history":[{"count":2,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2681\/revisions"}],"predecessor-version":[{"id":2685,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2681\/revisions\/2685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/2683"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=2681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=2681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=2681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}