{"id":2707,"date":"2022-06-03T12:35:57","date_gmt":"2022-06-03T10:35:57","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=2707"},"modified":"2023-06-06T16:53:30","modified_gmt":"2023-06-06T14:53:30","slug":"mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/","title":{"rendered":"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los pasados 18 y 19 de mayo MST holding particip\u00f3 en las jornadas de <strong>Distrito Digital (Parque Tecnol\u00f3gico de Alicante) <\/strong>con un debate sobre los <strong>\u201cErrores de la empresa tecnol\u00f3gica en la generaci\u00f3n y fidelizaci\u00f3n de clientes\u201d<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El d\u00eda 18 tuvo lugar una jornada de networking con el tejido empresarial local organizado por Relaciones Empresariales del Mediterr\u00e1neo (REM). Al d\u00eda siguiente tuvo lugar el debate en el que Grupo MST centr\u00f3 su ponencia en c\u00f3mo mejorar el negocio y la fidelizaci\u00f3n de los clientes en base a casos pr\u00e1cticos relacionados con la experiencia de MST Holding en la <strong>externalizaci\u00f3n de procesos de venta y posventa, Contact Centers, Mystery Shopping, consultor\u00eda de Customer Experience (CX), control de calidad emitida y percibida y desarrollo de tecnolog\u00eda<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento estuvo patrocinado por empresas y organizaciones l\u00edderes a nivel local como Ibercaja, Grupo Ant\u00f3n, Rotary, Relaciones Empresariales del Mediterr\u00e1neo (REM) y representantes de medios de comunicaci\u00f3n y entidades p\u00fablicas, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los temas tratados por Salvador Serra, Alberto Exp\u00f3sito y Paulino Borrell en representaci\u00f3n de Grupo MST, eAlicia y Consulting C3 respectivamente, se debatieron los siguientes tres puntos clave:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>La importancia de la posventa y fidelizaci\u00f3n de los clientes: <\/strong>como medio de generaci\u00f3n de negocio, tanto o m\u00e1s que la venta en s\u00ed misma.<\/li><li><strong>Como profesionalizar un equipo de ventas para alcanzar los objetivos: <\/strong>mediante roles especializados, entendiendo el funnel (embudo) de ventas, cualificando los leads, escalando los equipos y mediante la retroalimentaci\u00f3n.<\/li><li><strong>La necesidad de medir la calidad percibida adem\u00e1s de la emitida: <\/strong>mediante herramientas tecnol\u00f3gicas como eAlicia (<a href=\"http:\/\/www.ealicia.com\/\">www.ealicia.com<\/a>). Durante la ponencia, los participantes respondieron, en menos de un minuto, a una encuesta de satisfacci\u00f3n generada por eAlicia mediante un c\u00f3digo QR y su tel\u00e9fono pudiendo evaluar as\u00ed las funcionalidades y facilidad de uso de la aplicaci\u00f3n.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el evento, tuvo lugar la presentaci\u00f3n institucional de la Ocean Race, que tendr\u00e1 como primera escala Alicante en el mes de octubre de este a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MST holding y su divisi\u00f3n de tecnolog\u00eda (CTBU) siguen apoyando al tejido empresarial del pa\u00eds y todas aquellas iniciativas que generen riqueza a nivel local. M\u00e1s informaci\u00f3n en <a href=\"http:\/\/www.mstholding.com\/\">www.mstholding.com <\/a>y en <a href=\"http:\/\/www.consultingc3.com\/\">www.consultingc3.com<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed os dejamos el <a href=\"http:\/\/es el enlace al v\u00eddeo-resumen de las ponencias\">enlace al v\u00eddeo<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los pasados 18 y 19 de mayo MST holding particip\u00f3 en las jornadas de Distrito Digital (Parque Tecnol\u00f3gico de Alicante) con un debate sobre los \u201cErrores de la empresa tecnol\u00f3gica en la generaci\u00f3n y fidelizaci\u00f3n de clientes\u201d. El d\u00eda 18 tuvo lugar una jornada de networking con el tejido empresarial local organizado por Relaciones Empresariales [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-2707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas - MST Holding Blog<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"Los pasados 18 y 19 de mayo MST holding particip\u00f3 en las jornadas de Distrito Digital (Parque Tecnol\u00f3gico de Alicante) con un debate sobre los \u201cErrores de la empresa tecnol\u00f3gica en la generaci\u00f3n y fidelizaci\u00f3n de clientes\u201d. El d\u00eda 18 tuvo lugar una jornada de networking con el tejido empresarial local organizado por Relaciones Empresariales [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-06-03T10:35:57+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:53:30+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/06\/222222222222.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1177\" \/>\r\n\t<meta property=\"og:image:height\" content=\"777\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas\",\"datePublished\":\"2022-06-03T10:35:57+00:00\",\"dateModified\":\"2023-06-06T14:53:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/222222222222.png\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/\",\"name\":\"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/222222222222.png\",\"datePublished\":\"2022-06-03T10:35:57+00:00\",\"dateModified\":\"2023-06-06T14:53:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/222222222222.png\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/222222222222.png\",\"width\":1177,\"height\":777},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas - MST Holding Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/","og_locale":"es_ES","og_type":"article","og_title":"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas - MST Holding Blog","og_description":"Los pasados 18 y 19 de mayo MST holding particip\u00f3 en las jornadas de Distrito Digital (Parque Tecnol\u00f3gico de Alicante) con un debate sobre los \u201cErrores de la empresa tecnol\u00f3gica en la generaci\u00f3n y fidelizaci\u00f3n de clientes\u201d. El d\u00eda 18 tuvo lugar una jornada de networking con el tejido empresarial local organizado por Relaciones Empresariales [&hellip;]","og_url":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/","og_site_name":"MST Holding Blog","article_published_time":"2022-06-03T10:35:57+00:00","article_modified_time":"2023-06-06T14:53:30+00:00","og_image":[{"width":1177,"height":777,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/06\/222222222222.png","type":"image\/png"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas","datePublished":"2022-06-03T10:35:57+00:00","dateModified":"2023-06-06T14:53:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/06\/222222222222.png","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/","url":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/","name":"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/06\/222222222222.png","datePublished":"2022-06-03T10:35:57+00:00","dateModified":"2023-06-06T14:53:30+00:00","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/06\/222222222222.png","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/06\/222222222222.png","width":1177,"height":777},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-apoya-al-tejido-empresarial-en-alicante-con-sus-soluciones-tecnologicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"MST Holding apoya al tejido empresarial en Alicante con sus soluciones tecnol\u00f3gicas"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2022\/06\/222222222222.png","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=2707"}],"version-history":[{"count":2,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2707\/revisions"}],"predecessor-version":[{"id":2714,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/2707\/revisions\/2714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/2712"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=2707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=2707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=2707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}