{"id":3162,"date":"2023-01-09T13:27:49","date_gmt":"2023-01-09T12:27:49","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=3162"},"modified":"2023-06-06T16:51:03","modified_gmt":"2023-06-06T14:51:03","slug":"los-contact-centers-en-2023","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/","title":{"rendered":"LOS CONTACT CENTERS EN 2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aunque la pandemia de&nbsp;<strong>COVID-19<\/strong>&nbsp;empieza a quedar atr\u00e1s en varios aspectos, su impacto perdurar\u00e1 en otros \u00e1mbitos, como el laboral. Y uno de los sectores que se ha visto m\u00e1s afectado es el de los servicios de&nbsp;<strong>Atenci\u00f3n al Cliente<\/strong>, porque todos los \u2018actores\u2019 han modificado &#8211; de una forma u otra &#8211; su forma de interactuar con el entorno y ahora&nbsp;<strong>todo apunta que 2023 ser\u00e1 un a\u00f1o de consolidaci\u00f3n para estos cambios.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordemos que, a ra\u00edz del Coronavirus, los usuarios se mostraron\u00a0<strong>m\u00e1s dependientes de los canales telem\u00e1ticos<\/strong>\u00a0para solucionar sus problemas. Por su parte,\u00a0<strong>las empresas se tuvieron que adaptar para incorporar el teletrabajo a su actividad<\/strong>, mientras que los agentes debieron lidiar con\u00a0<strong>situaciones m\u00e1s exigentes y de mayor carga de trabajo<\/strong>. Unas tendencias que siguen en auge tres a\u00f1os despu\u00e9s.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>IMPORTANCIA DE LA EXPERIENCIA DEL EMPLEADO<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si las cosas funcionan bien dentro de la empresa y sus trabajadores son felices, es m\u00e1s f\u00e1cil que el negocio marche \u2018viento en popa\u2019. Y m\u00e1s en compa\u00f1\u00edas donde&nbsp;<strong>el servicio de Atenci\u00f3n al Cliente es primordial<\/strong>&nbsp;y cada operador es un \u2018embajador\u2019 de la marca.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>MAYOR OMNICANALIDAD<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A ra\u00edz de la pandemia, las compa\u00f1\u00edas tambi\u00e9n han entendido que estar en un \u00fanico canal es insuficiente para poder&nbsp;<strong>interactuar y mantenerse en contacto con sus clientes<\/strong>. Vivimos en un mundo digitalizado e interconectado donde los usuarios quieren multitud de alternativas para comunicarse (tel\u00e9fono, correo electr\u00f3nico, chat, Redes Sociales, videollamadas\u2026); por lo que, para competir mejor,&nbsp;<strong>es necesario tener presencia en todos los frentes posibles<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>LA NUBE COMO NUEVO ESPACIO DE TRABAJO<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la\u00a0<strong>consultora Gartner<\/strong>, en 2021 el 30 % de las cargas de trabajo en la nube se implementaban en plataformas nativas\u00a0<em><strong>\u2018cloud\u2019<\/strong><\/em>\u00a0(en la nube). Pues bien,\u00a0para 2025 la estimaci\u00f3n es que esta dato crecer\u00e1 hasta el 95 %. \u00bfLas razones? La\u00a0<strong>capacidad de escalabilidad<\/strong>\u00a0de este modelo de negocio y las enormes posibilidades que particularmente puede ofrecer a\u00a0<em><strong>Call Centers<\/strong><\/em>\u00a0y\u00a0<em><strong>Contact Centers<\/strong><\/em>, como mayor\u00a0<strong>Retorno de la Inversi\u00f3n (ROI)<\/strong>\u00a0o f\u00e1cil despliegue\/implantaci\u00f3n del servicio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>INVERSI\u00d3N EN AN\u00c1LISIS PARA MEJORAR EL CONOCIMIENTO<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A m\u00e1s informaci\u00f3n, m\u00e1s oportunidades para tomar buenas decisiones. Las empresas quieren saber\u00a0<strong>si est\u00e1n tomando buenas decisiones<\/strong>, tener capacidad para\u00a0<strong>monitorizar las campa\u00f1as que ponen en marcha<\/strong>\u00a0y\u00a0<strong>entender las decisiones de sus clientes<\/strong>. Y, para lograrlo, se est\u00e1n aprovechando de los avances tecnol\u00f3gicos que les permiten\u00a0<strong>obtener m\u00e9tricas (KPI\u2019s)<\/strong>\u00a0en tiempo real u obtener interesantes resultados en el\u00a0<strong>an\u00e1lisis de los sentimientos y emociones de sus propios agentes y\u00a0de sus clientes<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>SOFISTICACI\u00d3N EN LA IVR<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En 2020, los\u00a0<em>Call Centers<\/em>\u00a0en Espa\u00f1a\u00a0generaron un volumen de negocio el 0,8 % superior\u00a0al a\u00f1o anterior, ya que una de las consecuencias directas de la pandemia fue\u00a0<strong>el claro incremento en el n\u00famero de interacciones. La atenci\u00f3n telem\u00e1tica fue soluci\u00f3n para muchas personas<\/strong>\u00a0por la imposibilidad de gestionar sus incidencias de forma personal, y ahora estas ya se han acostumbrado a seguir haci\u00e9ndolo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para responder adecuadamente a esta mayor presi\u00f3n, las empresas de telemarketing pueden recurrir a herramientas sofisticadas de&nbsp;<strong>Respuesta de Voz Interactiva (IVR)<\/strong>. Gracias a las mejoras en&nbsp;<strong>Inteligencia Artificial (IA)<\/strong>&nbsp;y&nbsp;<strong>Procesamiento del Lenguaje Natural (PLN)<\/strong>, los&nbsp;<em>bots<\/em>&nbsp;que atienden las llamadas pueden&nbsp;<strong>hacerlo de forma mucho m\u00e1s humana que antes y descargar de trabajo<\/strong>&nbsp;a los agentes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>INCLUSI\u00d3N DE HERRAMIENTAS DE AUTOSERVICIO<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En ocasiones, los problemas que presentan los clientes son de f\u00e1cil soluci\u00f3n y ni siquiera requieren de la intervenci\u00f3n de un agente. Para estos casos, las empresas est\u00e1n empezando a ver con buenos ojos&nbsp;<strong>la utilizaci\u00f3n de herramientas de autoservicio<\/strong>&nbsp;que gu\u00eden a los usuarios por el camino correcto para resolver sus problemas. De esta forma, las llamadas&nbsp;<strong>se convierten en el \u00faltimo recurso<\/strong>&nbsp;para los casos en los que no hayan logrado lo que buscaban, lo que se traduce en&nbsp;<strong>colas con menor volumen de llamadas y menos tiempos de espera<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>INTELIGENCIA ARTIFICIAL PARA UNA EXPERIENCIA PERSONALIZADA<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Invertir en\u00a0<strong>Inteligencia Artificial (IA)<\/strong>\u00a0en este sector es una de las mejores formas de poner unos cimientos s\u00f3lidos para su negocio. Esta tecnolog\u00eda tiene multitud de aplicaciones y muchas de ellas\u00a0<strong>son de gran valor para<\/strong>\u00a0<strong>mejorar la experiencia de los clientes<\/strong>: desde personalizar el servicio a ofrecer respuestas precisas en tiempo real, pasando<strong>\u00a0incluso por predecir su comportamiento\u00a0<\/strong>para anticiparse antes de que se presenten los problemas.\u00a0 \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como ves, 2023 se presenta como un a\u00f1o apasionante para los<em><strong> Contact Centers<\/strong><\/em>. Sus frentes abiertos son numerosos, por lo que\u00a0<strong>este sector tiene un enorme potencial tanto humano como tecnol\u00f3gico<\/strong>\u00a0para seguir creciendo de forma satisfactoria a corto y largo plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.mstholding.com\">www.mstholding.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque la pandemia de&nbsp;COVID-19&nbsp;empieza a quedar atr\u00e1s en varios aspectos, su impacto perdurar\u00e1 en otros \u00e1mbitos, como el laboral. Y uno de los sectores que se ha visto m\u00e1s afectado es el de los servicios de&nbsp;Atenci\u00f3n al Cliente, porque todos los \u2018actores\u2019 han modificado &#8211; de una forma u otra &#8211; su forma de interactuar [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":3164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[340,3],"tags":[],"class_list":["post-3162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-call-center","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>LOS CONTACT CENTERS EN 2023 - MST Holding Blog<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"LOS CONTACT CENTERS EN 2023 - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"Aunque la pandemia de&nbsp;COVID-19&nbsp;empieza a quedar atr\u00e1s en varios aspectos, su impacto perdurar\u00e1 en otros \u00e1mbitos, como el laboral. Y uno de los sectores que se ha visto m\u00e1s afectado es el de los servicios de&nbsp;Atenci\u00f3n al Cliente, porque todos los \u2018actores\u2019 han modificado &#8211; de una forma u otra &#8211; su forma de interactuar [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-01-09T12:27:49+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:51:03+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/01\/33333.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"871\" \/>\r\n\t<meta property=\"og:image:height\" content=\"490\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"LOS CONTACT CENTERS EN 2023\",\"datePublished\":\"2023-01-09T12:27:49+00:00\",\"dateModified\":\"2023-06-06T14:51:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/\"},\"wordCount\":841,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/33333.jpg\",\"articleSection\":[\"call center\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/\",\"name\":\"LOS CONTACT CENTERS EN 2023 - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/33333.jpg\",\"datePublished\":\"2023-01-09T12:27:49+00:00\",\"dateModified\":\"2023-06-06T14:51:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/33333.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/33333.jpg\",\"width\":871,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/los-contact-centers-en-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LOS CONTACT CENTERS EN 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LOS CONTACT CENTERS EN 2023 - MST Holding Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/","og_locale":"es_ES","og_type":"article","og_title":"LOS CONTACT CENTERS EN 2023 - MST Holding Blog","og_description":"Aunque la pandemia de&nbsp;COVID-19&nbsp;empieza a quedar atr\u00e1s en varios aspectos, su impacto perdurar\u00e1 en otros \u00e1mbitos, como el laboral. Y uno de los sectores que se ha visto m\u00e1s afectado es el de los servicios de&nbsp;Atenci\u00f3n al Cliente, porque todos los \u2018actores\u2019 han modificado &#8211; de una forma u otra &#8211; su forma de interactuar [&hellip;]","og_url":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/","og_site_name":"MST Holding Blog","article_published_time":"2023-01-09T12:27:49+00:00","article_modified_time":"2023-06-06T14:51:03+00:00","og_image":[{"width":871,"height":490,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/01\/33333.jpg","type":"image\/jpeg"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"LOS CONTACT CENTERS EN 2023","datePublished":"2023-01-09T12:27:49+00:00","dateModified":"2023-06-06T14:51:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/"},"wordCount":841,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/01\/33333.jpg","articleSection":["call center","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/","url":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/","name":"LOS CONTACT CENTERS EN 2023 - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/01\/33333.jpg","datePublished":"2023-01-09T12:27:49+00:00","dateModified":"2023-06-06T14:51:03+00:00","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/01\/33333.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/01\/33333.jpg","width":871,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/los-contact-centers-en-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"LOS CONTACT CENTERS EN 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/01\/33333.jpg","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/3162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=3162"}],"version-history":[{"count":1,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/3162\/revisions"}],"predecessor-version":[{"id":3165,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/3162\/revisions\/3165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/3164"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=3162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=3162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=3162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}