{"id":3224,"date":"2023-02-23T12:18:12","date_gmt":"2023-02-23T11:18:12","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=3224"},"modified":"2023-06-06T16:50:43","modified_gmt":"2023-06-06T14:50:43","slug":"mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/","title":{"rendered":"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El d\u00eda 21 de Febrero MST Holding recibi\u00f3 el premio\u00a0<strong>CRECE2023<\/strong>\u00a0que recogi\u00f3 nuestra Directora\u00a0Jessica Barcel\u00f3\u00a0por nuestra nueva plataforma en Oporto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MT Holding recibi\u00f3 un reconocimiento por su destacado crecimiento en el \u00faltimo a\u00f1o impulsando su particular apuesta por los servicios BPO Contact Center Pan Europeos. El premio, otorgado por <strong>AEERC- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes<\/strong>, reconoce el compromiso y la dedicaci\u00f3n de la empresa por alcanzar el \u00e9xito y consolidarse en el mercado del sector del Contact Center aumentando su oferta de servicios de contact center multiling\u00fces con alta innovaci\u00f3n tecnol\u00f3gica para Europa: atenci\u00f3n al cliente, banca telef\u00f3nica, soporte t\u00e9cnico, televenta y back office.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el evento Jessica Barcel\u00f3 (Directora de MST Holding) recibi\u00f3 el galard\u00f3n de manos de Jos\u00e9 Francisco Rodr\u00edguez (Diretor de la AEERC), quien destac\u00f3 el gran esfuerzo y la visi\u00f3n empresarial de la compa\u00f1\u00eda para lograr un crecimiento sostenido en un entorno competitivo y cambiante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MST Holding ha demostrado una estrategia s\u00f3lida y un enfoque centrado en el cliente y la consolidaci\u00f3n internacional, lo que le ha permitido aumentar sus ventas y expandir su presencia en nuevos mercados. Adem\u00e1s, ha implementado innovaciones en sus servicios, adapt\u00e1ndose a las necesidades y tendencias del mercado del contact center.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En MST estamos muy orgullosos de recibir este premio que reconoce el trabajo en equipo y el esfuerzo constante que hemos realizado para lograr el crecimiento sostenido de la empresa. Este premio nos motiva a seguir trabajando en la mejora continua y a ofrecer soluciones de calidad a nuestros clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La entrega de este premio es una muestra de que el compromiso, la visi\u00f3n empresarial y la capacidad de adaptaci\u00f3n son factores clave para el \u00e9xito en el mundo de los negocios. MST Holding es un ejemplo de c\u00f3mo una empresa puede crecer y consolidarse en el mercado, manteniendo siempre un enfoque en la satisfacci\u00f3n del cliente y en la calidad de sus servicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este reconocimiento es un impulso para la empresa y una muestra de que est\u00e1 en el camino correcto hacia un futuro prometedor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.mstholding.com\">www.mstholding.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 21 de Febrero MST Holding recibi\u00f3 el premio\u00a0CRECE2023\u00a0que recogi\u00f3 nuestra Directora\u00a0Jessica Barcel\u00f3\u00a0por nuestra nueva plataforma en Oporto. MT Holding recibi\u00f3 un reconocimiento por su destacado crecimiento en el \u00faltimo a\u00f1o impulsando su particular apuesta por los servicios BPO Contact Center Pan Europeos. El premio, otorgado por AEERC- Asociaci\u00f3n Espa\u00f1ola de Expertos en la [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":3226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-3224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes - MST Holding Blog<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"El d\u00eda 21 de Febrero MST Holding recibi\u00f3 el premio\u00a0CRECE2023\u00a0que recogi\u00f3 nuestra Directora\u00a0Jessica Barcel\u00f3\u00a0por nuestra nueva plataforma en Oporto. MT Holding recibi\u00f3 un reconocimiento por su destacado crecimiento en el \u00faltimo a\u00f1o impulsando su particular apuesta por los servicios BPO Contact Center Pan Europeos. El premio, otorgado por AEERC- Asociaci\u00f3n Espa\u00f1ola de Expertos en la [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-02-23T11:18:12+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:50:43+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/02\/ffffffffffffff.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1065\" \/>\r\n\t<meta property=\"og:image:height\" content=\"698\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes\",\"datePublished\":\"2023-02-23T11:18:12+00:00\",\"dateModified\":\"2023-06-06T14:50:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/\"},\"wordCount\":392,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ffffffffffffff.jpg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/\",\"name\":\"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ffffffffffffff.jpg\",\"datePublished\":\"2023-02-23T11:18:12+00:00\",\"dateModified\":\"2023-06-06T14:50:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ffffffffffffff.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ffffffffffffff.jpg\",\"width\":1065,\"height\":698},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes - MST Holding Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/","og_locale":"es_ES","og_type":"article","og_title":"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes - MST Holding Blog","og_description":"El d\u00eda 21 de Febrero MST Holding recibi\u00f3 el premio\u00a0CRECE2023\u00a0que recogi\u00f3 nuestra Directora\u00a0Jessica Barcel\u00f3\u00a0por nuestra nueva plataforma en Oporto. MT Holding recibi\u00f3 un reconocimiento por su destacado crecimiento en el \u00faltimo a\u00f1o impulsando su particular apuesta por los servicios BPO Contact Center Pan Europeos. El premio, otorgado por AEERC- Asociaci\u00f3n Espa\u00f1ola de Expertos en la [&hellip;]","og_url":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/","og_site_name":"MST Holding Blog","article_published_time":"2023-02-23T11:18:12+00:00","article_modified_time":"2023-06-06T14:50:43+00:00","og_image":[{"width":1065,"height":698,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/02\/ffffffffffffff.jpg","type":"image\/jpeg"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes","datePublished":"2023-02-23T11:18:12+00:00","dateModified":"2023-06-06T14:50:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/"},"wordCount":392,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/02\/ffffffffffffff.jpg","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/","url":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/","name":"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/02\/ffffffffffffff.jpg","datePublished":"2023-02-23T11:18:12+00:00","dateModified":"2023-06-06T14:50:43+00:00","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/02\/ffffffffffffff.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/02\/ffffffffffffff.jpg","width":1065,"height":698},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-recoge-el-premio-crece23-de-manos-de-la-aeer-asociacion-espanola-de-expertos-en-la-relacion-con-clientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"MST Holding recoge el premio CRECE23 de manos de la AEER- Asociaci\u00f3n Espa\u00f1ola de Expertos en la Relaci\u00f3n con Clientes"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2023\/02\/ffffffffffffff.jpg","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/3224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=3224"}],"version-history":[{"count":3,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/3224\/revisions"}],"predecessor-version":[{"id":3229,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/3224\/revisions\/3229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/3226"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=3224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=3224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=3224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}