{"id":4523,"date":"2024-12-04T12:22:36","date_gmt":"2024-12-04T11:22:36","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=4523"},"modified":"2024-12-04T12:22:41","modified_gmt":"2024-12-04T11:22:41","slug":"mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/","title":{"rendered":"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Como parte de su firme compromiso con la responsabilidad social, MST Holding, l\u00edder en servicios de Atenci\u00f3n al Cliente, se ha unido nuevamente a la campa\u00f1a de Gran Recapte del Banco de Alimentos. Este evento anual moviliza a la sociedad para recolectar alimentos no perecederos destinados a personas en situaci\u00f3n de vulnerabilidad, garantizando as\u00ed el acceso a una alimentaci\u00f3n adecuada para quienes m\u00e1s lo necesitan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La donaci\u00f3n de MST Holding contribuir\u00e1 a ampliar el alcance del Banco de Alimentos, permitiendo asistir a un mayor n\u00famero de familias y personas que enfrentan circunstancias dif\u00edciles. Esta iniciativa refuerza el compromiso de MST Holding con su comunidad y su prop\u00f3sito de marcar una diferencia positiva en la vida de quienes necesitan apoyo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pedro Barcel\u00f3, CEO de MST Holding, expres\u00f3 su entusiasmo y dedicaci\u00f3n hacia la campa\u00f1a: \u00abEn MST Holding, creemos profundamente en el poder de la solidaridad y en la importancia de la responsabilidad compartida. Nos llena de orgullo participar en el Gran Recapte del Banco de Alimentos, una causa que refleja nuestros valores y nos permite ayudar activamente a nuestra comunidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Campa\u00f1a de Gran Recapte se desarrollar\u00e1 de forma simult\u00e1nea en los cuatro Bancos de Alimentos de Catalu\u00f1a, y MST Holding anima a sus empleados, socios comerciales y a la comunidad en general a unirse a la causa mediante la donaci\u00f3n de alimentos no perecederos y la participaci\u00f3n activa en esta iniciativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para obtener m\u00e1s informaci\u00f3n sobre la Campa\u00f1a de Gran Recapte y c\u00f3mo contribuir, visite <a href=\"http:\/\/www.granrecapte.com\">www.granrecapte.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre MST Holding:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MST Holding, expertos en gesti\u00f3n de clientes multicanal y en distintos idiomas, ofrece soluciones completas de Atenci\u00f3n al Cliente que satisfacen todas las necesidades de comunicaci\u00f3n de sus clientes. Con un compromiso inquebrantable hacia la excelencia y la responsabilidad social, MST Holding contin\u00faa fortaleciendo su impacto positivo en las comunidades donde opera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.mstholding.com\">www.mstholding.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de su firme compromiso con la responsabilidad social, MST Holding, l\u00edder en servicios de Atenci\u00f3n al Cliente, se ha unido nuevamente a la campa\u00f1a de Gran Recapte del Banco de Alimentos. Este evento anual moviliza a la sociedad para recolectar alimentos no perecederos destinados a personas en situaci\u00f3n de vulnerabilidad, garantizando as\u00ed el [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4524,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[340,3],"tags":[],"class_list":["post-4523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-call-center","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos - MST Holding Blog<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"Como parte de su firme compromiso con la responsabilidad social, MST Holding, l\u00edder en servicios de Atenci\u00f3n al Cliente, se ha unido nuevamente a la campa\u00f1a de Gran Recapte del Banco de Alimentos. Este evento anual moviliza a la sociedad para recolectar alimentos no perecederos destinados a personas en situaci\u00f3n de vulnerabilidad, garantizando as\u00ed el [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-12-04T11:22:36+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-12-04T11:22:41+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2024\/12\/11.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"675\" \/>\r\n\t<meta property=\"og:image:height\" content=\"715\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos\",\"datePublished\":\"2024-12-04T11:22:36+00:00\",\"dateModified\":\"2024-12-04T11:22:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/11.jpg\",\"articleSection\":[\"call center\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/\",\"name\":\"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/11.jpg\",\"datePublished\":\"2024-12-04T11:22:36+00:00\",\"dateModified\":\"2024-12-04T11:22:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/11.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/11.jpg\",\"width\":675,\"height\":715},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos - MST Holding Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/","og_locale":"es_ES","og_type":"article","og_title":"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos - MST Holding Blog","og_description":"Como parte de su firme compromiso con la responsabilidad social, MST Holding, l\u00edder en servicios de Atenci\u00f3n al Cliente, se ha unido nuevamente a la campa\u00f1a de Gran Recapte del Banco de Alimentos. Este evento anual moviliza a la sociedad para recolectar alimentos no perecederos destinados a personas en situaci\u00f3n de vulnerabilidad, garantizando as\u00ed el [&hellip;]","og_url":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/","og_site_name":"MST Holding Blog","article_published_time":"2024-12-04T11:22:36+00:00","article_modified_time":"2024-12-04T11:22:41+00:00","og_image":[{"width":675,"height":715,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2024\/12\/11.jpg","type":"image\/jpeg"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos","datePublished":"2024-12-04T11:22:36+00:00","dateModified":"2024-12-04T11:22:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2024\/12\/11.jpg","articleSection":["call center","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/","url":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/","name":"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2024\/12\/11.jpg","datePublished":"2024-12-04T11:22:36+00:00","dateModified":"2024-12-04T11:22:41+00:00","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2024\/12\/11.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2024\/12\/11.jpg","width":675,"height":715},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-se-une-un-ano-mas-a-la-campana-de-gran-recapte-del-banco-de-alimentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"MST Holding se une un a\u00f1o m\u00e1s a la Campa\u00f1a de Gran Recapte del Banco de Alimentos"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2024\/12\/11.jpg","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/4523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=4523"}],"version-history":[{"count":1,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/4523\/revisions"}],"predecessor-version":[{"id":4525,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/4523\/revisions\/4525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/4524"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=4523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=4523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=4523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}