{"id":4696,"date":"2025-06-06T14:32:14","date_gmt":"2025-06-06T12:32:14","guid":{"rendered":"https:\/\/www.mstholding.com\/blog\/?p=4696"},"modified":"2025-06-06T14:45:38","modified_gmt":"2025-06-06T12:45:38","slug":"mst-holding-presenta-nueva-unidad-bbi","status":"publish","type":"post","link":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/","title":{"rendered":"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En un encuentro cuidadosamente dise\u00f1ado para combinar estrategia, cercan\u00eda y visi\u00f3n de futuro, el 28 de mayo <strong>MST Holding celebr\u00f3 en Madrid la presentaci\u00f3n oficial de su nueva unidad de negocio, <em>BBI (Business Banking Innovation)<\/em><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acto, desarrollado en el Club Financiero G\u00e9nova, congreg\u00f3 a destacados representantes del mundo financiero, expertos en transformaci\u00f3n digital, perfiles directivos y medios especializados. Un formato \u00e1gil, que fusion\u00f3 una comida ejecutiva con una sesi\u00f3n de networking en la terraza del emblem\u00e1tico enclave madrile\u00f1o, sirvi\u00f3 de marco para introducir esta nueva propuesta del grupo, pensada para liderar la <a href=\"https:\/\/www.mstholding.com\/lp\/bbi-externalizacion-de-servicios-bancarios\/\" target=\"_blank\" rel=\"noreferrer noopener\">innovaci\u00f3n en el sector bancario<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BBI: el futuro de la banca ya est\u00e1 aqu\u00ed<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La unidad BBI nace como una respuesta a la necesidad de modernizaci\u00f3n de las entidades financieras, con un enfoque basado en tecnolog\u00eda, eficiencia y experiencia del cliente. Liderada por <strong>Javier S\u00e1ez<\/strong>, profesional con m\u00e1s de 20 a\u00f1os de experiencia en banca comercial y direcci\u00f3n financiera, BBI se posiciona como un gran el socio estrat\u00e9gico que acompa\u00f1ar\u00e1 a las entidades en su evoluci\u00f3n digital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la comida, <strong>Pedro Barcel\u00f3<\/strong>, presidente de MST Holding, dio la bienvenida a los asistentes y comparti\u00f3 una visi\u00f3n clara: <em>\u201cDesde la unidad de innovaci\u00f3n bancaria combinamos visi\u00f3n estrat\u00e9gica, tecnol\u00f3gica, y conocimiento real del sector bancario acompa\u00f1ando a las entidades financieras en su transformaci\u00f3n, maximizando resultados y mejorando la relaci\u00f3n con sus clientes\u201d<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Javier S\u00e1ez explic\u00f3 con detalle los fundamentos sobre los que se asienta BBI. Enfatiz\u00f3 la importancia de automatizar procesos internos que tradicionalmente han sido costosos y lentos, as\u00ed como de introducir soluciones digitales que permitan tomar decisiones de forma m\u00e1s \u00e1gil, con datos en tiempo real y con una visi\u00f3n centrada en el cliente. Seg\u00fan S\u00e1ez, la clave del \u00e9xito en el entorno bancario actual reside en combinar el conocimiento profundo del sector con una capacidad tecnol\u00f3gica de respuesta inmediata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tecnolog\u00eda aplicada a resultados concretos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo del encuentro, se presentaron los tres ejes de actuaci\u00f3n de BBI. Una metodolog\u00eda basada en los pilares fundamentales que sustentan la diferenciaci\u00f3n e innovaci\u00f3n de la unidad:<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li><strong>Consultor\u00eda bancaria previa:<\/strong> Contamos con una unidad especializada en consultor\u00eda que, antes de implementar nuestros servicios, analiza en profundidad las distintas opciones para optimizar procesos. Este an\u00e1lisis se realiza considerando la estrategia de la entidad, sus necesidades, pol\u00edticas y entorno, con el objetivo de adaptarnos completamente a su realidad, ya sea en el front office o en el back office.<br><br><\/li>\n\n\n\n<li><strong>Tecnolog\u00eda propia desarrollada para la banca:<\/strong> Disponemos de soluciones tecnol\u00f3gicas creadas internamente, espec\u00edficamente para el sector bancario. Estas herramientas permiten optimizar procesos sin depender de proveedores externos, integr\u00e1ndose de forma natural en las arquitecturas, entornos y formas de operar del cliente, sin alterar su ecosistema.<br><br><\/li>\n\n\n\n<li><strong>Gestores certificados:<\/strong> La ejecuci\u00f3n de procesos de optimizaci\u00f3n e innovaci\u00f3n es liderada por un equipo de gestores especializados, con experiencia en banca y seguros. Todos ellos cuentan con las certificaciones necesarias, lo que garantiza una trazabilidad escalable y una gesti\u00f3n end-to-end de los procesos acordados.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se mostraron algunas de las herramientas que ya componen el porfolio de BBI, como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.mstholding.com\/lp\/bbi-optima360-carteras-sobredimensionadas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Optima360<\/a><\/strong>, para gesti\u00f3n inteligente de carteras sobredimensionadas.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.mstholding.com\/lp\/bbi-connect-gestion-campanas-comerciales\/\" target=\"_blank\" rel=\"noreferrer noopener\">BBI Connect<\/a><\/strong>, que permite una gesti\u00f3n multicanal de campa\u00f1as comerciales.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.mstholding.com\/lp\/bbi-ehereditas-gestion-de-testamentarias\/\" target=\"_blank\" rel=\"noreferrer noopener\">eHereditas<\/a><\/strong>, para gesti\u00f3n de herencias con automatizaci\u00f3n y eficiencia<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.mstholding.com\/lp\/bbi-swiftbankops-optimizacion-de-procesos\/\" target=\"_blank\" rel=\"noreferrer noopener\">SwiftBankOps<\/a><\/strong>, que permite maximizar la rentabilidad optimizando la gesti\u00f3n administrativa.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A diferencia de propuestas estandarizadas, BBI pone el foco en soluciones configurables, modulares y f\u00e1cilmente integrables, capaces de escalar seg\u00fan la madurez digital del cliente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un espacio para la conversaci\u00f3n y la colaboraci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la parte m\u00e1s institucional, los asistentes pudieron disfrutar de una sesi\u00f3n de networking en la terraza del Club Financiero, un entorno distendido desde el que se abrieron conversaciones clave sobre el futuro del sector. El ambiente relajado y la cercan\u00eda entre perfiles directivos generaron un clima propicio para el intercambio de ideas, experiencias y visiones estrat\u00e9gicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temas como la <a href=\"https:\/\/www.mstholding.com\/lp\/bbi-optima360-carteras-sobredimensionadas\/\" target=\"_blank\" rel=\"noreferrer noopener\">inteligencia artificial aplicada a la banca<\/a>, los nuevos modelos de relaci\u00f3n cliente-entidad o la necesidad de agilizar los procesos regulatorios estuvieron muy presentes en las conversaciones, as\u00ed como la reflexi\u00f3n sobre la importancia de contar con aliados tecnol\u00f3gicos capaces de aportar respuestas r\u00e1pidas a los retos del d\u00eda a d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este espacio informal no solo permiti\u00f3 afianzar v\u00ednculos entre los asistentes, sino tambi\u00e9n fortalecer el posicionamiento de BBI como un proyecto con vocaci\u00f3n de comunidad: una unidad que no solo presta servicios, sino que escucha, comparte y evoluciona junto a sus clientes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Una nueva etapa para MST Holding<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con la puesta en marcha de BBI, MST Holding da un paso firme hacia la consolidaci\u00f3n de su liderazgo en la innovaci\u00f3n dentro del \u00e1mbito BPO y la transformaci\u00f3n digital. Esta nueva unidad se suma a un ecosistema de servicios ya consolidado, ampliando la capacidad del grupo para responder a los desaf\u00edos m\u00e1s complejos del mercado financiero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero m\u00e1s all\u00e1 de su oferta tecnol\u00f3gica, BBI representa una nueva forma de mirar al sector. Una forma m\u00e1s humana, m\u00e1s cercana y m\u00e1s centrada en resultados sostenibles. Una apuesta por la excelencia, no solo operativa, sino tambi\u00e9n relacional.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>BBI: innovaci\u00f3n con prop\u00f3sito<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El evento de presentaci\u00f3n de BBI no fue simplemente una cita corporativa; fue una declaraci\u00f3n de principios. MST Holding deja claro, una vez m\u00e1s, que su compromiso con el futuro del sector financiero va mucho m\u00e1s all\u00e1 de la tecnolog\u00eda. Implica visi\u00f3n, acompa\u00f1amiento y una apuesta firme por la mejora continua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">BBI arranca con fuerza, con una propuesta centrada en transformar, no en imponer. En sumar valor, no en sustituir. En colaborar desde la cercan\u00eda y el conocimiento. Y, sobre todo, en abrir una nueva etapa en la que las entidades bancarias cuenten con un socio que habla su mismo idioma, entiende sus retos y comparte su ambici\u00f3n de construir un futuro m\u00e1s \u00e1gil, inteligente y orientado a las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un encuentro cuidadosamente dise\u00f1ado para combinar estrategia, cercan\u00eda y visi\u00f3n de futuro, el 28 de mayo MST Holding celebr\u00f3 en Madrid la presentaci\u00f3n oficial de su nueva unidad de negocio, BBI (Business Banking Innovation). El acto, desarrollado en el Club Financiero G\u00e9nova, congreg\u00f3 a destacados representantes del mundo financiero, expertos en transformaci\u00f3n digital, perfiles [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[48],"tags":[],"class_list":["post-4696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid - MST Holding Blog<\/title>\r\n<meta name=\"description\" content=\"La unidad BBI nace como una respuesta a la necesidad de modernizaci\u00f3n de las entidades financieras, con un enfoque basado en tecnolog\u00eda, eficiencia y experiencia del cliente.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid - MST Holding Blog\" \/>\r\n<meta property=\"og:description\" content=\"La unidad BBI nace como una respuesta a la necesidad de modernizaci\u00f3n de las entidades financieras, con un enfoque basado en tecnolog\u00eda, eficiencia y experiencia del cliente.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MST Holding Blog\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-06-06T12:32:14+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-06-06T12:45:38+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2025\/06\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Raquel\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/\"},\"author\":{\"name\":\"Raquel\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\"},\"headline\":\"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid\",\"datePublished\":\"2025-06-06T12:32:14+00:00\",\"dateModified\":\"2025-06-06T12:45:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/\"},\"wordCount\":1062,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/\",\"name\":\"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid - MST Holding Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg\",\"datePublished\":\"2025-06-06T12:32:14+00:00\",\"dateModified\":\"2025-06-06T12:45:38+00:00\",\"description\":\"La unidad BBI nace como una respuesta a la necesidad de modernizaci\u00f3n de las entidades financieras, con un enfoque basado en tecnolog\u00eda, eficiencia y experiencia del cliente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/mst-holding-presenta-nueva-unidad-bbi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"name\":\"MST Holding Blog\",\"description\":\"Todo lo que debes saber a cerca de las novedades de MST Holding.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#organization\",\"name\":\"MST Holding Blog\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-mstholding_logo-2.jpg\",\"width\":480,\"height\":213,\"caption\":\"MST Holding Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/#\\\/schema\\\/person\\\/9487f58c917c4ddf28cf4a0db8443af4\",\"name\":\"Raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g\",\"caption\":\"Raquel\"},\"url\":\"https:\\\/\\\/www.mstholding.com\\\/blog\\\/author\\\/raquels\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid - MST Holding Blog","description":"La unidad BBI nace como una respuesta a la necesidad de modernizaci\u00f3n de las entidades financieras, con un enfoque basado en tecnolog\u00eda, eficiencia y experiencia del cliente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/","og_locale":"es_ES","og_type":"article","og_title":"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid - MST Holding Blog","og_description":"La unidad BBI nace como una respuesta a la necesidad de modernizaci\u00f3n de las entidades financieras, con un enfoque basado en tecnolog\u00eda, eficiencia y experiencia del cliente.","og_url":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/","og_site_name":"MST Holding Blog","article_published_time":"2025-06-06T12:32:14+00:00","article_modified_time":"2025-06-06T12:45:38+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2025\/06\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg","type":"image\/jpeg"}],"author":"Raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raquel","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/#article","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/"},"author":{"name":"Raquel","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4"},"headline":"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid","datePublished":"2025-06-06T12:32:14+00:00","dateModified":"2025-06-06T12:45:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/"},"wordCount":1062,"commentCount":0,"publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2025\/06\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/","url":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/","name":"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid - MST Holding Blog","isPartOf":{"@id":"https:\/\/www.mstholding.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/#primaryimage"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2025\/06\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg","datePublished":"2025-06-06T12:32:14+00:00","dateModified":"2025-06-06T12:45:38+00:00","description":"La unidad BBI nace como una respuesta a la necesidad de modernizaci\u00f3n de las entidades financieras, con un enfoque basado en tecnolog\u00eda, eficiencia y experiencia del cliente.","breadcrumb":{"@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/#primaryimage","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2025\/06\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2025\/06\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.mstholding.com\/blog\/mst-holding-presenta-nueva-unidad-bbi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mstholding.com\/blog\/"},{"@type":"ListItem","position":2,"name":"MST Holding presenta oficialmente su nueva unidad BBI en un evento exclusivo en Madrid"}]},{"@type":"WebSite","@id":"https:\/\/www.mstholding.com\/blog\/#website","url":"https:\/\/www.mstholding.com\/blog\/","name":"MST Holding Blog","description":"Todo lo que debes saber a cerca de las novedades de MST Holding.","publisher":{"@id":"https:\/\/www.mstholding.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mstholding.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mstholding.com\/blog\/#organization","name":"MST Holding Blog","url":"https:\/\/www.mstholding.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","contentUrl":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2019\/07\/cropped-mstholding_logo-2.jpg","width":480,"height":213,"caption":"MST Holding Blog"},"image":{"@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mstholding.com\/blog\/#\/schema\/person\/9487f58c917c4ddf28cf4a0db8443af4","name":"Raquel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad079b609afe14a66d2677dedd9c859cd0786efd48bf77f82fddc5f5e292459?s=96&d=mm&r=g","caption":"Raquel"},"url":"https:\/\/www.mstholding.com\/blog\/author\/raquels\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.mstholding.com\/blog\/wp-content\/uploads\/2025\/06\/MST-unidad-BBI-externalizacion-servicios-bancarios.jpg","_links":{"self":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/4696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/comments?post=4696"}],"version-history":[{"count":2,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/4696\/revisions"}],"predecessor-version":[{"id":4701,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/posts\/4696\/revisions\/4701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media\/4695"}],"wp:attachment":[{"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/media?parent=4696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/categories?post=4696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mstholding.com\/blog\/wp-json\/wp\/v2\/tags?post=4696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}